{"id":12593,"date":"2021-11-18T16:45:00","date_gmt":"2021-11-18T15:45:00","guid":{"rendered":"https:\/\/www.biancoscuro.it\/site\/?p=12593"},"modified":"2021-11-26T11:28:30","modified_gmt":"2021-11-26T10:28:30","slug":"la-biblioteca-fregene-gino-pallotta-presenta-due-incontri-su-dante","status":"publish","type":"post","link":"https:\/\/www.biancoscuro.it\/site\/la-biblioteca-fregene-gino-pallotta-presenta-due-incontri-su-dante\/","title":{"rendered":"La Biblioteca Fregene Gino Pallotta presenta due incontri su Dante"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">\u23f0 lettura <\/span> <span class=\"rt-time\"> 2<\/span> <span class=\"rt-label rt-postfix\">min. <br><br><\/span><\/span>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"736\" src=\"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/11\/primo-incontro-su-dante-1024x736.jpg\" alt=\"\" class=\"wp-image-12594\" srcset=\"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/11\/primo-incontro-su-dante-1024x736.jpg 1024w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/11\/primo-incontro-su-dante-300x216.jpg 300w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/11\/primo-incontro-su-dante-768x552.jpg 768w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/11\/primo-incontro-su-dante-600x431.jpg 600w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/11\/primo-incontro-su-dante-1536x1104.jpg 1536w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/11\/primo-incontro-su-dante-1320x949.jpg 1320w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/11\/primo-incontro-su-dante.jpg 1587w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:22px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La <em>Biblioteca Fregene Gino Pallotta<\/em> concluder\u00e0 le iniziative dell\u2019anno 2021 offrendo al pubblico due eventi su <strong>Dante Alighieri <\/strong>e aprir\u00e0 la stagione culturale del 2022 con uno dei pi\u00f9 conosciuti ed amati artisti internazionali, <strong>Gustav Klimt<\/strong>.<\/p>\n\n\n\n<p>Infatti, in occasione delle grandi mostre in corso a Roma, \u201cInferno\u201d alle Scuderie del Quirinale e \u201cKlimt. La Secessione e l\u2019Italia\u201d a Palazzo Braschi, la Biblioteca ha organizzato tre incontri, curati dallo storico dell\u2019arte <strong>Sandro Polo<\/strong>, che mirano ad approfondire le tematiche delle esposizioni ancorandole ai contesti storici sociali, artistici e culturali.<\/p>\n\n\n\n<p>Il giorno <strong>27 novembre alle ore 18.00<\/strong> presso la Casa della Partecipazione di Maccarese si svolger\u00e0 l\u2019incontro <strong>\u201cArte e vita quotidiana ai tempi di Dante\u201d: <\/strong>Sandro Polo parler\u00e0 delle scoperte scientifiche, degli usi, dei costumi e dei grandi cantieri fiorentini dell\u2019epoca di Dante, espressione di quel nuovo modo di pensare che costituir\u00e0 la premessa alla nascita del Rinascimento toscano. Nel Duecento e per buona parte del Trecento Firenze vive un momento di straordinaria fioritura culturale, economica e demografica che la trasformarono in una delle metropoli pi\u00f9 grandi e importanti dell\u2019epoca: in questo contesto dinamico e creativo vivono e si esprimono i due principali artefici di una nuova, rivoluzionaria cultura: Dante e Giotto. Nell\u2019anno in cui ricorre il settimo centenario della morte di Dante la conferenza rappresenta un omaggio della Biblioteca al Poeta.<\/p>\n\n\n\n<p>Il giorno <strong>11 dicembre alle ore 18.00 <\/strong>presso la Casa della Partecipazione di Maccarese, l\u2019incontro <strong>\u201cL\u2019immaginario dantesco nella storia dell\u2019arte\u201d <\/strong>costituisce un\u2019introduzione alla mostra \u201cInferno\u201d -visitabile fino al 9 gennaio 2022- che racconta l\u2019iconografia del mondo dei dannati, dal Medioevo ai nostri giorni. <strong>Sandro Polo<\/strong> illustrer\u00e0, contestualizzandoli, alcuni fra gli oltre 200 capolavori esposti alle Scuderie del Quirinale e si soffermer\u00e0 sulla diffusione e il senso del revival gotico che ha caratterizzato buona parte dell\u2019architettura eclettica ottocentesca italiana. Coloro che vorranno approfondire ulteriormente il percorso della mostra potranno visionare il catalogo in biblioteca.<\/p>\n\n\n\n<p>Infine il <strong>5 gennaio alle ore 18.00<\/strong>, sempre presso la Casa della Partecipazione di Maccarese, la Biblioteca apre la nuova stagione culturale con l\u2019incontro <strong>\u201cKlimt e la Secessione Viennese\u201d<\/strong>. A cavallo tra Ottocento e Novecento Vienna appare come una capitale europea elegante e pacata dolcemente sospesa tra i valzer e le operette di Strauss e Lehar. Dietro questa facciata rassicurante la citt\u00e0 \u00e8 scossa da forti tensioni sociali che ne stanno minando le fondamenta. Una stupefacente presenza di artisti e intellettuali intercetta e indaga le inquietudini e i sottili cambiamenti in corso alla luce delle sconvolgenti novit\u00e0 freudiane. L\u2019opera di Klimt rispecchia fedelmente le contraddizioni di questo periodo: il suo lavoro, pur risplendendo di aurea bellezza, \u00e8 attraversato da linee e immagini nervose, da un eros potente e misterioso che ammalia e allarma. Klimt non va oltre, rimane uno splendido e irrequieto tramonto sulla Storia; saranno i drammatici linguaggi di Schiele, Kokoschka, Schoenberg e molti altri ad anticipare quell\u2019abisso verso cui Vienna e tutta l\u2019Europa stanno inesorabilmente scivolando: la I Guerra Mondiale. Coloro che vorranno approfondire ulteriormente il percorso della mostra potranno visionare il catalogo in biblioteca.<\/p>\n\n\n\n<p>Per rispettare adeguatamente le norme anti-Covid la Biblioteca ha deciso di organizzare gli incontri presso la Casa della Partecipazione di Maccarese che garantisce un sereno distanziamento.<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\"><strong>INFO<\/strong>\n<strong>Incontro<\/strong>\n<strong>Arte e vita quotidiana ai tempi di Dante<\/strong>\nA cura di Sandro Polo\n27 novembre 2021 ore 18.00\n\n<strong>Incontro<\/strong>\n<strong>L\u2019immaginario dantesco nella storia dell\u2019arte<\/strong>\nA cura di Sandro Polo\n11 dicembre 2021 ore 18.00\n\n<strong>Incontro<\/strong> \n<strong>Klimt e la Secessione Viennese<\/strong>\nA cura di Sandro Polo\n5 gennaio alle ore 18.00\n\n<strong>Casa della Partecipazione\n<\/strong>Via del Buttero, 10 - Maccarese (Fiumicino - RM)\n\n<strong>Biblioteca Fregene Gino Pallotta\nViale della Pineta 140 - Fregene\u00a0<\/strong>\nbibliofregene@libero.it\nwww.bibliotecafregene.com<\/pre>\n\n\n\n<div style=\"height:26px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">\u23f0 lettura <\/span> <span class=\"rt-time\"> 2<\/span> <span class=\"rt-label rt-postfix\">min. <\/p>\n<p><\/span><\/span>La Biblioteca Fregene Gino Pallotta concluder\u00e0 le iniziative dell\u2019anno 2021 offrendo al pubblico due eventi su Dante Alighieri e aprir\u00e0 la stagione culturale del 2022 con uno dei pi\u00f9 conosciuti ed amati artisti internazionali, Gustav Klimt. Infatti, in occasione delle grandi mostre in corso a Roma, \u201cInferno\u201d alle Scuderie del Quirinale e \u201cKlimt. La Secessione&hellip;&nbsp;<a href=\"https:\/\/www.biancoscuro.it\/site\/la-biblioteca-fregene-gino-pallotta-presenta-due-incontri-su-dante\/\" rel=\"bookmark\">Leggi tutto &raquo;<span class=\"screen-reader-text\">La Biblioteca Fregene Gino Pallotta presenta due incontri su Dante<\/span><\/a><\/p>\n","protected":false},"author":980,"featured_media":12594,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"footnotes":""},"categories":[5,26],"tags":[],"class_list":["post-12593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte","category-eventi"],"jetpack_featured_media_url":"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/11\/primo-incontro-su-dante.jpg","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":12775,"url":"https:\/\/www.biancoscuro.it\/site\/incontro-klimt-e-la-secessione-viennese\/","url_meta":{"origin":12593,"position":0},"title":"Incontro: Klimt e la Secessione viennese","author":"Roberta Melasecca","date":"13 Gennaio 2022","format":false,"excerpt":"La Biblioteca Fregene Gino Pallotta apre la nuova stagione culturale 2022 con l\u2019incontro \u201cKlimt e la Secessione Viennese\u201d, a cura di Sandro Polo e in concomitanza con la mostra \u201cKlimt. La Secessione e l\u2019Italia\u201d a Palazzo Braschi.L\u2019appuntamento \u00e8 sabato 15 gennaio ore 16 e ore 18 presso la Casa della\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2022\/01\/Incontro-Klimt.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2022\/01\/Incontro-Klimt.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2022\/01\/Incontro-Klimt.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2022\/01\/Incontro-Klimt.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2022\/01\/Incontro-Klimt.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":19363,"url":"https:\/\/www.biancoscuro.it\/site\/dante-nei-libri-dartista\/","url_meta":{"origin":12593,"position":1},"title":"Dante nei libri d&#8217;artista","author":"Roberta Melasecca","date":"15 Marzo 2026","format":false,"excerpt":"Il 25 marzo, in occasione del Danted\u00ec, lo scenografico Salone Borromini di Roma accoglie 30 interpretazioni plastiche e visive dell'universo dantesco. Un cortocircuito affascinante tra i manoscritti storici della biblioteca e le sperimentazioni materiche di 30 artisti contemporanei. Ci sono libri fatti per essere letti e libri nati per essere\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/03\/Copertina-Dante-nei-libri-dartista.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/03\/Copertina-Dante-nei-libri-dartista.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/03\/Copertina-Dante-nei-libri-dartista.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/03\/Copertina-Dante-nei-libri-dartista.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/03\/Copertina-Dante-nei-libri-dartista.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":5786,"url":"https:\/\/www.biancoscuro.it\/site\/gustav-klimt-al-mudec\/","url_meta":{"origin":12593,"position":2},"title":"Gustav Klimt al MUDEC","author":"Lucia Garnero","date":"22 Agosto 2017","format":false,"excerpt":"L\u2019allestimento espositivo a celebrare il Gesamtkunstwerk \u00c8\u00a0stato inaugurato il 26 luglio, e sar\u00e0 aperto fino al 7 gennaio 2018, l\u2019evento espositivo \u201cKlimt Experience\u201d, rappresentazione multimediale totalmente immersiva dedicata al padre fondatore della secessione viennese. Non solo la vita, le figure e i paesaggi di Gustav Klimt, ma anche la pittura,\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"Le proiezioni interagiscono con l\u2019ambiente che le ospita, ridisegnandolo e valorizzandolo. I motivi tratti dai dipinti pi\u00f9 celebri del grande artista rivestono lo spazio e avvolgono lo spettatore. Particolare e texture ispirate a G. Klimt, L\u2019albero della vita, dal Fregio per Palazzo Stoclet a Bruxelles.","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2017\/08\/03klimt.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2017\/08\/03klimt.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2017\/08\/03klimt.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2017\/08\/03klimt.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2017\/08\/03klimt.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2017\/08\/03klimt.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":1468,"url":"https:\/\/www.biancoscuro.it\/site\/al-centro-nevralgico-dello-jugendstil-larte-di-klimt-a-milano-2\/","url_meta":{"origin":12593,"position":3},"title":"Al centro nevralgico dello Jugendstil, l\u2019Arte di Klimt a Milano","author":"Redazione BIANCOSCURO","date":"26 Giugno 2014","format":false,"excerpt":"Gustav Klimt fino al 13 luglio a Milano! Il mito di Gustav Klimt pu\u00f2 essere considerato un racconto sacro che d\u00e0 la risposta agli interrogativi degli uomini e proietta la coscienza collettiva verso una spiegazione di come l\u2019arte moderna internazionale, attraverso la Secessione Viennese, assurse ad una completa dissoluzione dai\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"kllimt rivista d'arte biancoscuro art magazine","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2014\/06\/kllimt.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2014\/06\/kllimt.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2014\/06\/kllimt.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":3922,"url":"https:\/\/www.biancoscuro.it\/site\/antonella-nardi-giuliana-silvestrini-vincitori-oltre-libri-larte-del-presente-incontra-libri-del-passato-biblioteca-angelica-roma\/","url_meta":{"origin":12593,"position":4},"title":"Antonella Nardi e Giuliana Silvestrini tra i vincitori di \u201cOltre i libri \u2013 l\u2019arte del presente incontra i libri del passato\u201d \u2013 Biblioteca Angelica Roma","author":"Roberta Melasecca","date":"18 Maggio 2016","format":false,"excerpt":"Antonella Nardi, Scritture infinite e mappature nascoste, particolare \u00a0 Antonella Nardi e Giuliana Silvestrini tra i vincitori di \u201cOltre i libri \u2013 l\u2019arte del presente incontra i libri del passato\u201d \u2013 Biblioteca Angelica Roma Inaugurazione mostra: 26 maggio 2016 ore 18.30 | Biblioteca Angelica | Roma \u00a0 Antonella Nardi e\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/05\/scritture-infinite-e-mappature-nascoste-particolare-web.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/05\/scritture-infinite-e-mappature-nascoste-particolare-web.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/05\/scritture-infinite-e-mappature-nascoste-particolare-web.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":7971,"url":"https:\/\/www.biancoscuro.it\/site\/carlo-cecchi-matinee\/","url_meta":{"origin":12593,"position":5},"title":"Carlo Cecchi &#8211; Matin\u00e9e","author":"Roberta Melasecca","date":"10 Ottobre 2018","format":false,"excerpt":"Carlo CecchiMatin\u00e9ea cura di Paola Pallotta Inaugurazione 14 ottobre 2018 ore 11.30 | SBA Sporting Beach Arte | Roma Arte e cultura possono curare un territorio difficile e controverso come quello di Ostia, incoraggiandone le potenzialit\u00e0 e favorendone la rinascita. Con impegno convinto, lo storico stabilimento balneare Sporting Beach apre\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/10\/Carlo-Cecchi-giallo-mare.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/10\/Carlo-Cecchi-giallo-mare.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/10\/Carlo-Cecchi-giallo-mare.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/10\/Carlo-Cecchi-giallo-mare.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/10\/Carlo-Cecchi-giallo-mare.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/10\/Carlo-Cecchi-giallo-mare.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/12593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/users\/980"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/comments?post=12593"}],"version-history":[{"count":0,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/12593\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/media\/12594"}],"wp:attachment":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/media?parent=12593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/categories?post=12593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/tags?post=12593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}