{"id":12621,"date":"2021-11-29T16:50:45","date_gmt":"2021-11-29T15:50:45","guid":{"rendered":"https:\/\/www.biancoscuro.it\/site\/?p=12621"},"modified":"2021-12-01T17:02:26","modified_gmt":"2021-12-01T16:02:26","slug":"manuel-canelles-in-vitro","status":"publish","type":"post","link":"https:\/\/www.biancoscuro.it\/site\/manuel-canelles-in-vitro\/","title":{"rendered":"Manuel Canelles &#8211; In Vitro"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">\u23f0 lettura <\/span> <span class=\"rt-time\"> 2<\/span> <span class=\"rt-label rt-postfix\">min. <br><br><\/span><\/span>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/11\/In-Vitro-1-683x1024.jpg\" alt=\"\" class=\"wp-image-12622\" srcset=\"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/11\/In-Vitro-1-683x1024.jpg 683w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/11\/In-Vitro-1-200x300.jpg 200w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/11\/In-Vitro-1-768x1152.jpg 768w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/11\/In-Vitro-1-600x900.jpg 600w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/11\/In-Vitro-1-1024x1536.jpg 1024w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/11\/In-Vitro-1.jpg 1200w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Venerd\u00ec 3 dicembre 2021 alle ore 18.30, presso <em>00a gallery<\/em> di Merano c\/o Villa Dolores, via Laurin 18, verr\u00e0 inaugurata <strong>IN VITRO, <\/strong>esposizione personale dell\u2019artista <strong>Manuel Canelles<\/strong>, presentata in forma di studio.<\/p>\n\n\n\n<p><em>In Vitro<\/em> \u00e8 un progetto che ha origine da un\u2019esperienza personale dell\u2019artista il quale in Alsazia, guidato dai racconti di una famiglia ebraica, si mette alla ricerca di uno spazio enorme e sconvolgente. Un\u2019insieme di architetture industriali che venivano utilizzate come fabbriche di materiali bellici all\u2019interno del quale centinaia di persone di origini ebraica venivano \u201cutilizzate\u201d fino allo stremo. Nessuno sa pi\u00f9 nulla di preciso di quel luogo. Il velo di oblio che \u00e8 caduto su di esso annulla la certezza che esso si realmente esistito. \u00c8 ancor meno sicuro che sia questo il luogo di cui parlava il racconto.&nbsp;L\u2019artista gioca su questa incertezza e sul mistero che filtra dalle vetrate, in una sorta di contemplazione visiva, al confine tra la suggestione gotica e l\u2019esperimento in laboratorio. Canelles non ritrae solamente la natura che si riappropria di uno spazio umano (contrappasso inevitabile del cambiamento climatico) ma di organismi che si svelano attraverso il nostro sguardo, trattando l\u2019elemento dell\u2019ombra e dell\u2019oscurit\u00e0 come paradigmi ingranditi, da cui non prendere le distanze, ma anzi con cui prendere confidenza. Dice l\u2019artista: \u00abCosa ci fosse nei vetri stento tuttora a dirlo. Se fossero creature del passato che gettano la loro luce sul presente o il contrario. So che il mio occhio, il mio corpo, la mia esperienza psichica ne hanno respirato il balenare improvviso.\u00bb<\/p>\n\n\n\n<p>Nel testo del catalogo il critico <em>Michele Fucich<\/em> continua: \u00abDifficile dire cosa sia questo guardare &#8211; o vedere &#8211; quando ogni finestra presuppone un fuori. Se qui un fuori c&#8217;\u00e8, si fa percepire sbiadito, a frammenti: alla stregua di squarci di vecchie albumine o di paesaggi pittorici ottocenteschi ritagliati ed apposti. Il dentro a cui ci si riferisce \u00e8 in s\u00e9 un\u2019altra cosa. La cornice presto scompare in questo <em>vedere col corpo.<\/em> I vetri divengono <em>lastre.&nbsp;<\/em>\u201cIn vitro\u201d \u00e8 un affiorare di \u201cimmagini dialettiche\u201d nel senso benjaminiano dell\u2019incontro con un passato presunto, che non \u00e8 il passato, ma che ci viene incontro unendo fulmineamente l\u2019\u201c\u00e8 stato\u201d e l\u2019\u201cadesso\u201d, forse un \u201cdomani\u201d, per poi di nuovo perdersi nel vortice che l\u2019ha generato, come ad ogni risveglio.\u00bb<\/p>\n\n\n\n<p><strong>Manuel Canelles<\/strong>, artista e curatore, si muove da oltre vent\u2019anni in un territorio al confine fra video, fotografia, installazione e performance. La sua ricerca indaga la condizione provvisoria e ambigua della memoria,&nbsp;problematizzando il confine tra realt\u00e0 e rappresentazione e ponendo al centro della ricerca l&#8217;enigmaticit\u00e0 dello spazio e l\u2019indefinitezza dei corpi che lo abitano. I suoi lavori partecipano ai pi\u00f9 rilevanti eventi di arte contemporanea.&nbsp;<\/p>\n\n\n\n<div style=\"height:17px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<pre class=\"wp-block-preformatted\"><strong>INFO<\/strong>\nManuel Canelles\nIn Vitro\n\nInaugurazione 3 dicembre 2021 ore 18.30\nFino al 23 dicembre 2021\n\n00a gallery\nVilla Dolores\nVia Laurin 18 \nMerano (BZ)\nwww.00agallery.com<\/pre>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">\u23f0 lettura <\/span> <span class=\"rt-time\"> 2<\/span> <span class=\"rt-label rt-postfix\">min. <\/p>\n<p><\/span><\/span>Venerd\u00ec 3 dicembre 2021 alle ore 18.30, presso 00a gallery di Merano c\/o Villa Dolores, via Laurin 18, verr\u00e0 inaugurata IN VITRO, esposizione personale dell\u2019artista Manuel Canelles, presentata in forma di studio. In Vitro \u00e8 un progetto che ha origine da un\u2019esperienza personale dell\u2019artista il quale in Alsazia, guidato dai racconti di una famiglia ebraica,&hellip;&nbsp;<a href=\"https:\/\/www.biancoscuro.it\/site\/manuel-canelles-in-vitro\/\" rel=\"bookmark\">Leggi tutto &raquo;<span class=\"screen-reader-text\">Manuel Canelles &#8211; In Vitro<\/span><\/a><\/p>\n","protected":false},"author":980,"featured_media":12629,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"footnotes":""},"categories":[5,26,8,24],"tags":[],"class_list":["post-12621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte","category-eventi","category-fotografia","category-mostre"],"jetpack_featured_media_url":"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/11\/1-copia.jpg","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":12054,"url":"https:\/\/www.biancoscuro.it\/site\/manuel-canelles-posso-dirti-la-verita\/","url_meta":{"origin":12621,"position":0},"title":"Manuel Canelles &#8211; Posso dirti la verit\u00e0?","author":"Roberta Melasecca","date":"3 Luglio 2021","format":false,"excerpt":"Manuel CanellesOn StagePosso dirti la verit\u00e0?A cura di Roberta Melasecca Opening partecipativa e presentazione catalogo 7 luglio 2021 ore 19.00Centro TreviVia dei Cappuccini 28 - Bolzano Fino al 15 luglio 2021 Il giorno 7 luglio 2021 alle ore 19.00 il Centro Trevi di Bolzano ospita la quarta tappa del progetto\u2026","rel":"","context":"In &quot;editoria&quot;","block_context":{"text":"editoria","link":"https:\/\/www.biancoscuro.it\/site\/category\/editoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/07\/invito-copia.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/07\/invito-copia.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/07\/invito-copia.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/07\/invito-copia.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":18616,"url":"https:\/\/www.biancoscuro.it\/site\/voices_100-tributo-a-luciano-berio\/","url_meta":{"origin":12621,"position":1},"title":"VOICES_100 Tributo a Luciano Berio\u00a0","author":"Roberta Melasecca","date":"21 Giugno 2025","format":false,"excerpt":"Dal 7 al 10 luglio 2025, il Centro Trevi di Bolzano ospita il progetto VOICES_100 - Tributo a Luciano Berio\u00a0per i 100 anni dalla nascita del compositore, promosso da Spazio5 artecontemporanea. Inaugurazione 7 luglio 2025 dalle 18.30 alle 20.00.\u00a0 VOICES_01 nasce dall\u2019incontro tra il maestro Roberto Fabbriciani, flautista di fama\u2026","rel":"","context":"In &quot;installazioni&quot;","block_context":{"text":"installazioni","link":"https:\/\/www.biancoscuro.it\/site\/category\/installazioni\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/06\/VOICES_100-Tributo-a-Luciano-Berio.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/06\/VOICES_100-Tributo-a-Luciano-Berio.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/06\/VOICES_100-Tributo-a-Luciano-Berio.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/06\/VOICES_100-Tributo-a-Luciano-Berio.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":17821,"url":"https:\/\/www.biancoscuro.it\/site\/pixel-reprogramming-reality-festival-multidisciplinare-sullimmagine-digitale\/","url_meta":{"origin":12621,"position":2},"title":"PIXEL: Reprogramming Reality\u00a0","author":"Roberta Melasecca","date":"30 Ottobre 2024","format":false,"excerpt":"Festival Multidisciplinare sull\u2019Immagine Digitale Dal 15 al 22 novembre 2024, Bolzano ospiter\u00e0 la prima edizione di PIXEL, festival nato con l\u2019intento di esplorare il concetto di immagine in una societ\u00e0 sempre pi\u00f9 definita e influenzata dal sovraccarico di dati digitali.\u00a0 La manifestazione intende indagare come le immagini \u2013 dagli scatti\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2024\/10\/invito-pixel-1024x341.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2024\/10\/invito-pixel-1024x341.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2024\/10\/invito-pixel-1024x341.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2024\/10\/invito-pixel-1024x341.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":12820,"url":"https:\/\/www.biancoscuro.it\/site\/ugo-la-pietra-ovunque-a-casa-propria-film-e-video-1973-2015\/","url_meta":{"origin":12621,"position":3},"title":"Ugo La Pietra &#8211; Ovunque a casa propria. Film e video 1973\/2015","author":"Roberta Melasecca","date":"25 Gennaio 2022","format":false,"excerpt":"Si aprir\u00e0 il 10 febbraio 2022 alle ore 18.00 al TreviLab Centro Trevi di Bolzano il progetto Ovunque a casa propria, in assoluto il primo approfondimento espositivo sulla ricerca cinematografica e sulle sperimentazioni audiovisive di Ugo La Pietra, instancabile sperimentatore della percezione visiva. In mostra anche le videoinstallazioni contemporanee di\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2022\/01\/Ugo-La-Pietra.-La-Grande-Occasione-foto-di-copertina-della-mostra-Foto-Aurelia-Raffo-copia.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2022\/01\/Ugo-La-Pietra.-La-Grande-Occasione-foto-di-copertina-della-mostra-Foto-Aurelia-Raffo-copia.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2022\/01\/Ugo-La-Pietra.-La-Grande-Occasione-foto-di-copertina-della-mostra-Foto-Aurelia-Raffo-copia.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2022\/01\/Ugo-La-Pietra.-La-Grande-Occasione-foto-di-copertina-della-mostra-Foto-Aurelia-Raffo-copia.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":3786,"url":"https:\/\/www.biancoscuro.it\/site\/impronte-confessioni-itineranti-unanima-colori\/","url_meta":{"origin":12621,"position":4},"title":"Impronte. Le confessioni itineranti di Manuela Manes","author":"Redazione BIANCOSCURO","date":"28 Aprile 2016","format":false,"excerpt":"Deodato Arte \u00a0invita ad un viaggio nel colore con la mostra personale di Manuela Manes Gioved\u00ec 5 maggio presso la galleria Deodato Arte in\u00a0via Carlo Pisacane 36 a\u00a0Milano, alle ore 18,30 si inaugura la mostra personale di Manuela Manes dal titolo \"Impronte. Confessioni itineranti di un'anima a colori\".\u00a0 L'esposizione, curata\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/04\/Manuela-Manes.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/04\/Manuela-Manes.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/04\/Manuela-Manes.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/04\/Manuela-Manes.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":10308,"url":"https:\/\/www.biancoscuro.it\/site\/munari-in-movimento-prima-parte\/","url_meta":{"origin":12621,"position":5},"title":"Munari &#8211; In movimento | Prima parte","author":"Roberta Melasecca","date":"29 Gennaio 2020","format":false,"excerpt":"Inaugurazione 7 febbraio 2020 ore 18.00Centro Trevi - la piazza della culturaVia dei Cappuccini 28 - BolzanoFino al 28 febbraio 2020 L'Associazione Culturale Teatro Pratiko in collaborazione con il Centro Culturale Trevi - la piazza della cultura presenta la prima parte del progetto Munari - In movimento, a cura di\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2020\/01\/BRUNO-MUNARI.-Vetrini-a-luce-polarizzata.-Materiali-vari.-Courtesy-Miroslava-Hajek.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2020\/01\/BRUNO-MUNARI.-Vetrini-a-luce-polarizzata.-Materiali-vari.-Courtesy-Miroslava-Hajek.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2020\/01\/BRUNO-MUNARI.-Vetrini-a-luce-polarizzata.-Materiali-vari.-Courtesy-Miroslava-Hajek.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2020\/01\/BRUNO-MUNARI.-Vetrini-a-luce-polarizzata.-Materiali-vari.-Courtesy-Miroslava-Hajek.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/12621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/users\/980"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/comments?post=12621"}],"version-history":[{"count":0,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/12621\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/media\/12629"}],"wp:attachment":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/media?parent=12621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/categories?post=12621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/tags?post=12621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}