{"id":13787,"date":"2022-07-11T14:40:00","date_gmt":"2022-07-11T12:40:00","guid":{"rendered":"https:\/\/www.biancoscuro.it\/site\/?p=13787"},"modified":"2022-07-17T16:59:05","modified_gmt":"2022-07-17T14:59:05","slug":"dal-buio-alla-luce-from-darkness-to-light","status":"publish","type":"post","link":"https:\/\/www.biancoscuro.it\/site\/dal-buio-alla-luce-from-darkness-to-light\/","title":{"rendered":"Dal buio alla luce \/ From darkness to light"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">\u23f0 lettura <\/span> <span class=\"rt-time\"> 2<\/span> <span class=\"rt-label rt-postfix\">min. <br><br><\/span><\/span>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"999\" height=\"899\" src=\"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2022\/07\/Dal-buio-alla-luce-opera.jpg\" alt=\"\" class=\"wp-image-13825\" srcset=\"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2022\/07\/Dal-buio-alla-luce-opera.jpg 999w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2022\/07\/Dal-buio-alla-luce-opera-300x270.jpg 300w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2022\/07\/Dal-buio-alla-luce-opera-768x691.jpg 768w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2022\/07\/Dal-buio-alla-luce-opera-600x540.jpg 600w\" sizes=\"auto, (max-width: 999px) 100vw, 999px\" \/><figcaption>Carlo Guzzi, &#8220;Impronte di umanit\u00e0 di passaggi\u201c, ferro cotto, legno. 100x100x230 cm.<\/figcaption><\/figure>\n\n\n\n<p>Un progetto inserito nel panorama artistico delle mostre organizzate da SEA Aeroporti Linate Malpensa. Quattro artisti, un contesto diverso, dove il focus \u00e8 dare speranza, luce e bellezza in un momento storico difficile.<\/p>\n\n\n\n<p>Stiamo vivendo un\u2019epoca storica alquanto incerta, prima per la pandemia adesso per la guerra, evento che ci ha sconvolto tutti per la portata di violenza a cui mai avremmo voluto assistere. In questo senso abbiamo scelto a quattro artisti che ciascuno con il loro lavoro e con i materiali che utilizzano possono riaccendere una nuova speranza di luce. Una speranza data dalle forme dei marmi che si stagliano verso l\u2019alto e dai metalli dal titolo Visions che vogliono essere uno sguardo aperto al futuro di Vincenzo Lo Sasso; Jacopo Foggini per l\u2019utilizzo del colore applicato ad un materiale come la plastica (estruso di metacrilato e policarbornato) che rende la sua installazione un percorso vero e proprio fatto dai passeggeri i quali attraversando Malpensa possono ammirare una vera rinascita di luce; Carlo Guzzi che con i suoi uomini di metallo e legno ben rappresentano (non solo metaforicamente) i passeggeri che tornano a vivere dopo tanto buio. Ultimo ma non meno importante Davide Paglia che con i suoi particolari lavori in plexiglass mette in risalto attraverso i colori l\u2019energia emanata dai colori stessi. Quattro artisti per dare un nuovo volto all\u2019aeroporto in una visione immersa fatta di materiali, colori e forme che ben si adattano allo spazio e che ben rappresentano la forza del potere della luce. Le loro opere \u201cparlano\u201d pi\u00f9 di quanto si possa descrivere\u2026&nbsp;<\/p>\n\n\n\n<p>Artisti in mostra in una location differente dalle usuali: Jacopo Foggini, Carlo Guzzi, Vincenzo Lo Sasso, Davide Paglia&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"999\" height=\"706\" src=\"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2022\/07\/Dal-buio-alla-luce-locandina.jpg\" alt=\"\" class=\"wp-image-13824\" srcset=\"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2022\/07\/Dal-buio-alla-luce-locandina.jpg 999w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2022\/07\/Dal-buio-alla-luce-locandina-300x212.jpg 300w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2022\/07\/Dal-buio-alla-luce-locandina-768x543.jpg 768w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2022\/07\/Dal-buio-alla-luce-locandina-600x424.jpg 600w\" sizes=\"auto, (max-width: 999px) 100vw, 999px\" \/><\/figure>\n\n\n\n<pre class=\"wp-block-preformatted\"> <\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Aeroporto di Milano Malpensa<br \/>Terminal 1, Corridoio Imbarchi Extra Schengen - Satellite Centrale<br \/>14 luglio 2022 - 31 dicembre 2022<br \/>Ingresso libero se in possesso di un boarding pass<\/pre>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">\u23f0 lettura <\/span> <span class=\"rt-time\"> 2<\/span> <span class=\"rt-label rt-postfix\">min. <\/p>\n<p><\/span><\/span>Un progetto inserito nel panorama artistico delle mostre organizzate da SEA Aeroporti Linate Malpensa. Quattro artisti, un contesto diverso, dove il focus \u00e8 dare speranza, luce e bellezza in un momento storico difficile. Stiamo vivendo un\u2019epoca storica alquanto incerta, prima per la pandemia adesso per la guerra, evento che ci ha sconvolto tutti per la&hellip;&nbsp;<a href=\"https:\/\/www.biancoscuro.it\/site\/dal-buio-alla-luce-from-darkness-to-light\/\" rel=\"bookmark\">Leggi tutto &raquo;<span class=\"screen-reader-text\">Dal buio alla luce \/ From darkness to light<\/span><\/a><\/p>\n","protected":false},"author":1054,"featured_media":13825,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"footnotes":""},"categories":[5,26,334,24,6,7],"tags":[461],"class_list":["post-13787","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte","category-eventi","category-installazioni","category-mostre","category-pittura","category-scultura","tag-arte-contemporanea"],"jetpack_featured_media_url":"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2022\/07\/Dal-buio-alla-luce-opera.jpg","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":17898,"url":"https:\/\/www.biancoscuro.it\/site\/annalaura-di-luggo-oculus-spei\/","url_meta":{"origin":13787,"position":0},"title":"Annalaura di Luggo &#8211; Oculus-Spei","author":"Roberta Melasecca","date":"30 Novembre 2024","format":false,"excerpt":"Sar\u00e0 presentata al pubblico, al Pantheon di Roma, marted\u00ec 3 dicembre 2024 alle ore 18.30 Oculus-Spei, un\u2019installazione multimediale interattiva dell\u2019artista Annalaura di Luggo con il patrocinio morale del Giubileo e del Ministero degli Affari Esteri e della Cooperazione Internazionale.\u00a0 L\u2019appuntamento coincide con la Giornata internazionale dei diritti delle persone con\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2024\/12\/01_Backstage_Oculus_Spei.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2024\/12\/01_Backstage_Oculus_Spei.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2024\/12\/01_Backstage_Oculus_Spei.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2024\/12\/01_Backstage_Oculus_Spei.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2024\/12\/01_Backstage_Oculus_Spei.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":18530,"url":"https:\/\/www.biancoscuro.it\/site\/anna-romanello-acqua-luce-spiritualita\/","url_meta":{"origin":13787,"position":1},"title":"Anna Romanello &#8211; Acqua, luce, spiritualit\u00e0","author":"Roberta Melasecca","date":"22 Maggio 2025","format":false,"excerpt":"Mercoled\u00ec 4 giugno 2025 alle ore 19:00 la Fondazione Rezza Pro Cultura et Caritate presenta la mostra personale Acqua, Luce, Spiritualit\u00e0 di Anna Romanello a cura di Claudio Cremonesi, accompagnata da un saggio introduttivo di Michele Tarroni.\u00a0 Gli spazi della Chiesa di Santa Maria Annunziata in Borgo si apriranno ad\u2026","rel":"","context":"In &quot;mostre&quot;","block_context":{"text":"mostre","link":"https:\/\/www.biancoscuro.it\/site\/category\/mostre\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/05\/Anna-Romanello-Fontana-di-Nettuno-2001-30x21-cm-opera-fotografica-con-interventi-pastelli-ad-olio-e-acrilico.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/05\/Anna-Romanello-Fontana-di-Nettuno-2001-30x21-cm-opera-fotografica-con-interventi-pastelli-ad-olio-e-acrilico.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/05\/Anna-Romanello-Fontana-di-Nettuno-2001-30x21-cm-opera-fotografica-con-interventi-pastelli-ad-olio-e-acrilico.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/05\/Anna-Romanello-Fontana-di-Nettuno-2001-30x21-cm-opera-fotografica-con-interventi-pastelli-ad-olio-e-acrilico.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":11300,"url":"https:\/\/www.biancoscuro.it\/site\/capolavori-divisionisti-on-line-tour-virtuale-della-grande-mostra-a-novara-in-attesa-della-riapertura\/","url_meta":{"origin":13787,"position":2},"title":"Capolavori divisionisti on line","author":"Chiara","date":"25 Novembre 2020","format":false,"excerpt":"Tour virtuale della grande mostra a Novara in attesa della riapertura Attendendo la riapertura al pubblico delle mostre e dei musei in tutta Italia, sono diversi gli eventi espositivi attualmente fruibili sul web. E' il caso della grande mostra dedicata al Divisionismo italiano DIVISIONISMO La rivoluzione della luce REWIND al\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2020\/11\/DIVISIONISMO-27-Quinsac.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2020\/11\/DIVISIONISMO-27-Quinsac.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2020\/11\/DIVISIONISMO-27-Quinsac.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2020\/11\/DIVISIONISMO-27-Quinsac.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2020\/11\/DIVISIONISMO-27-Quinsac.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2020\/11\/DIVISIONISMO-27-Quinsac.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":8146,"url":"https:\/\/www.biancoscuro.it\/site\/presentazione-del-catalogo-la-luce-diversa-catania-palmieri-sanna%ef%bb%bf\/","url_meta":{"origin":13787,"position":3},"title":"PRESENTAZIONE DEL CATALOGO &#8220;La luce diversa Catania&#8221; | Palmieri | Sanna\ufeff","author":"Roberta Melasecca","date":"4 Novembre 2018","format":false,"excerpt":"Mercoled\u00ec 14 novembre 2018 ore 18.00Sala Auditorium Palazzo delle EsposizioniVia Nazionale 194 - Roma Il giorno 14 novembre 2018 alle ore 18.00 verr\u00e0 presentato, presso la Sala Auditorium del Palazzo delle Esposizioni, il catalogo della mostra La luce diversa, Lucilla Catania | Claudio Palmieri | Sandro Sanna, a cura di\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/11\/sala-comune-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/11\/sala-comune-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/11\/sala-comune-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/11\/sala-comune-2.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/11\/sala-comune-2.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":6556,"url":"https:\/\/www.biancoscuro.it\/site\/stefania-fabrizi-disegno-cabina\/","url_meta":{"origin":13787,"position":4},"title":"Stefania Fabrizi \u201cDisegno in cabina\u201d","author":"Roberta Melasecca","date":"20 Febbraio 2018","format":false,"excerpt":"Sabato 24 febbraio 2018 alle ore 18.00 SBA Sporting Beach ARTE presenta \u201cDisegno in cabina\u201d di Stefania Fabrizi a cura di Paola Pallotta. SBA Sporting Beach ARTE \u00e8 un nuovo contenitore di eventi d\u2019arte, la cui unicit\u00e0 \u00e8 nella sua ubicazione, Ostia, quartiere sul mare della capitale che da tempo\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/02\/disegno-in-cabina-stefania-fabrizi-web1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/02\/disegno-in-cabina-stefania-fabrizi-web1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/02\/disegno-in-cabina-stefania-fabrizi-web1.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":15451,"url":"https:\/\/www.biancoscuro.it\/site\/spazio-luce-colore-nellopera-di-marcello-grottesi\/","url_meta":{"origin":13787,"position":5},"title":"Spazio, luce, colore nell\u2019opera di Marcello Grottesi","author":"Roberta Melasecca","date":"4 Febbraio 2023","format":false,"excerpt":"Torna negli spazi di Micro a distanza di un anno l\u2019opera di Marcello Grottesi, con un percorso espositivo completamente nuovo, arricchito di opere e fotografie inedite. Il ciclo di mostre - voluto dai figli Pier Paolo e Clarissa Grottesi con il supporto organizzativo di Paola Valori - ha lo scopo\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2023\/02\/Invito-Spazio-luce-colore-nellopera-di-Marcello-Grottesi-copia.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/13787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/users\/1054"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/comments?post=13787"}],"version-history":[{"count":0,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/13787\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/media\/13825"}],"wp:attachment":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/media?parent=13787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/categories?post=13787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/tags?post=13787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}