{"id":17371,"date":"2024-06-03T13:09:47","date_gmt":"2024-06-03T11:09:47","guid":{"rendered":"https:\/\/www.biancoscuro.it\/site\/?p=17371"},"modified":"2024-06-04T17:57:57","modified_gmt":"2024-06-04T15:57:57","slug":"biancoscuro-leditoriale-di-vincenzo-chetta-64-giugno-luglio-2024","status":"publish","type":"post","link":"https:\/\/www.biancoscuro.it\/site\/biancoscuro-leditoriale-di-vincenzo-chetta-64-giugno-luglio-2024\/","title":{"rendered":"BIANCOSCURO, l\u2019editoriale di Vincenzo Chetta &#8211; #64 giugno\/luglio 2024"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">\u23f0 lettura <\/span> <span class=\"rt-time\"> 2<\/span> <span class=\"rt-label rt-postfix\">min. <br><br><\/span><\/span>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"999\" height=\"749\" src=\"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2024\/06\/999-IMG_2778-Il-Padiglione-Venezia-La-Biennale-di-Venezia-\u00a9-Ph.-liberementi.jpg\" alt=\"\" class=\"wp-image-17374\" srcset=\"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2024\/06\/999-IMG_2778-Il-Padiglione-Venezia-La-Biennale-di-Venezia-\u00a9-Ph.-liberementi.jpg 999w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2024\/06\/999-IMG_2778-Il-Padiglione-Venezia-La-Biennale-di-Venezia-\u00a9-Ph.-liberementi-300x225.jpg 300w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2024\/06\/999-IMG_2778-Il-Padiglione-Venezia-La-Biennale-di-Venezia-\u00a9-Ph.-liberementi-768x576.jpg 768w\" sizes=\"auto, (max-width: 999px) 100vw, 999px\" \/><figcaption class=\"wp-element-caption\"><em>Il Padiglione Venezia &#8211; La Biennale di Venezia &#8211; Ph.liberementi<\/em><\/figcaption><\/figure>\n\n\n\n<p>Aprile \u00e8 stato un mese impegnativo, l\u2019evento per la presentazione dell\u2019opera phygital <em>\u201cLe 4 note di Beethoven\u201d<\/em> di <strong>Svetlana Borisova<\/strong>, artista internazionale che abbiamo il piacere di avere in copertina su questo numero, \u00e8 stato un successo, alto l\u2019interesse delle persone all\u2019interno della location, il <strong>MonteCarlo Bay,<\/strong> che da anni accoglie i nostri eventi personalizzati. Altamente soddisfacente anche la rassegna <strong>Art fair di Zurigo<\/strong>, ottima la presenza di pubblico, preparato e interessato, che ha saputo dare il giusto spessore alla fiera.&nbsp;<\/p>\n\n\n\n<p>Rimaniamo in Svizzera, ma parliamo del presente e futuro, ovvero della citt\u00e0 di Basilea, dove tutto \u00e8&nbsp; pronto per l\u2019edizione 2024 di <strong>Art Basel<\/strong>, non solo nel consueto spazio fieristico, ma anche all\u2019<strong>Art Basel Riverboats<\/strong> (crociere artistiche sul Reno) e alla <strong>Fondazione Beyeler<\/strong>, che accoglie <em>\u201cSummer Show\u201d<\/em>, una mostra innovativa che comprende l\u2019intero spazio per una presentazione sperimentale di arte contemporanea.<\/p>\n\n\n\n<p>Attendiamo sempre con impazienza il mese di giugno, quando arriva il momento di partire per Basilea, l\u2019aria frizzante che senti in redazione \u00e8 estremamente contagiosa! La prospettiva di immergersi nell\u2019atmosfera vibrante di Art Basel, attorniati dalle gallerie d\u2019arte pi\u00f9 rinomate del mondo, \u00e8 davvero elettrizzante. <strong>Art Basel ci accoglie nel Magazine sector come ogni anno<\/strong>, e siamo molto curiosi di vedere le novit\u00e0 che porteranno le grandi gallerie coinvolte, una fra tutte riguarda sicuramente il progetto, nella sezione Unlimited, di <strong>Tornabuoni con Emilio Isgr\u00f2, e l\u2019opera \u201cEncyclop\u00e6dia Britannica 1969\u201d<\/strong>, opera monumentale di circa 24 metri.<\/p>\n\n\n\n<p>Non so se \u00e8 un caso, ma le edizioni di <strong>Art Basel<\/strong> in concomitanza con la <strong>Biennale di Venezia<\/strong> sono sempre le pi\u00f9 interessanti, e sono sicuro sar\u00e0 cos\u00ec!<\/p>\n\n\n\n<p>A proposito della <strong>\u201c60\u00aa Biennale &#8211; Stranieri Ovunque\u201d<\/strong>, la Biennale inclusiva di <strong>Adriano Pedrosa<\/strong>, vi consiglio il reportage fotografico completo sulla pagina <a href=\"https:\/\/www.facebook.com\/BiancoscuroArtMagazine\/\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook di Biancoscuro<\/a> (<a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.814366974058920&amp;type=3\" target=\"_blank\" rel=\"noreferrer noopener\">Album 1<\/a> &#8211; <a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.814897107339240&amp;type=3\" target=\"_blank\" rel=\"noreferrer noopener\">Album 2<\/a> &#8211; <a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.816537330508551&amp;type=3\" target=\"_blank\" rel=\"noreferrer noopener\">Album 3<\/a> &#8211; <a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.818617143633903&amp;type=3\" target=\"_blank\" rel=\"noreferrer noopener\">Album 4<\/a>), oltre alle pagine che abbiamo dedicato su questo numero.<\/p>\n\n\n\n<p>La 60\u00aa Biennale \u00e8 stata davvero interessante, forse il nostro entusiasmo nel visitare le anteprime \u00e8 dato anche dal fatto di esservi<strong> presenti con la doppia copertina dedicata all collettivo Claire Fontaine ed al titolo della 60\u00aa edizione <em>\u201cStranieri Ovunque &#8211; Foreigners Everywhere\u201d<\/em>, un\u2019occasione molto importante per BIANCOSCURO<\/strong>.<\/p>\n\n\n\n<p>Tornando con i piedi per terra <em>(per poco)<\/em> torniamo a&nbsp; prepararci per Basilea senza dimenticare che sono aperte le iscrizioni per l\u2019<strong>11\u00aa edizione del BIANCOSCURO Art Contest &#8211; Monte-Carlo Edition<\/strong>, l\u2019unico concorso d\u2019arte meritocratico che mette in palio la pubblicazione sulla copertina di BIANCOSCURO Art Magazine, oltre a tanti nuovi premi, come <strong>le importanti&nbsp; esposizioni a Parigi e Monte-Carlo.&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>La cerimonia finale \u00e8 prevista per il 21 settembre al MonteCarlo Bay<\/strong>, dove verranno presentate <strong>TUTTE le opere iscritte e TUTTI gli artisti partecipanti<\/strong>. Come da prassi fino a quel giorno non si sapr\u00e0 nulla dei vincitori, infatti verr\u00e0 mantenuto il massimo riserbo. Lo so, questa cosa crea tensione, ma \u00e8 questa una delle caratteristiche del nostro concorso, e siamo sempre molto contenti dei complimenti che riceviamo per lo Staff e per l\u2019organizzazione dell\u2019evento. E adesso <strong>presto, che tanta nuova arte mi aspetta<\/strong>!&nbsp;<\/p>\n\n\n\n<p><strong>Buona lettura<\/strong>, e se ci seguite anche sui social, <strong>buona visione&nbsp;<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"103\" src=\"http:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2015\/10\/firmaVincenzoChettaDirettoreBiancoscuro-300x103.jpg\" alt=\"Vincenzo Chetta Direttore Biancoscuro\" class=\"wp-image-3226\" srcset=\"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2015\/10\/firmaVincenzoChettaDirettoreBiancoscuro-300x103.jpg 300w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2015\/10\/firmaVincenzoChettaDirettoreBiancoscuro.jpg 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<p>Vincenzo Chetta<br \/>Direttore<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Seguici sulle nostre pagine <strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/BiancoscuroArtMagazine\/\" target=\"_blank\">Facebook<\/a><\/strong> e <strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.instagram.com\/biancoscuromag\/\" target=\"_blank\">Instagram<\/a><\/strong> <\/h2>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">\u23f0 lettura <\/span> <span class=\"rt-time\"> 2<\/span> <span class=\"rt-label rt-postfix\">min. <\/p>\n<p><\/span><\/span>Aprile \u00e8 stato un mese impegnativo, l\u2019evento per la presentazione dell\u2019opera phygital \u201cLe 4 note di Beethoven\u201d di Svetlana Borisova, artista internazionale che abbiamo il piacere di avere in copertina su questo numero, \u00e8 stato un successo, alto l\u2019interesse delle persone all\u2019interno della location, il MonteCarlo Bay, che da anni accoglie i nostri eventi personalizzati.&hellip;&nbsp;<a href=\"https:\/\/www.biancoscuro.it\/site\/biancoscuro-leditoriale-di-vincenzo-chetta-64-giugno-luglio-2024\/\" rel=\"bookmark\">Leggi tutto &raquo;<span class=\"screen-reader-text\">BIANCOSCURO, l\u2019editoriale di Vincenzo Chetta &#8211; #64 giugno\/luglio 2024<\/span><\/a><\/p>\n","protected":false},"author":909,"featured_media":17376,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"footnotes":""},"categories":[470,5,32,15],"tags":[40,449,461,185,583,452,464,2120,408],"class_list":["post-17371","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-art-magazine","category-arte","category-editoria","category-rivista-darte","tag-art-magazine","tag-arte","tag-arte-contemporanea","tag-biancoscuro-art-magazine","tag-editoriale","tag-fotografia","tag-milano","tag-rivista-darte","tag-vincenzo-chetta"],"jetpack_featured_media_url":"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2024\/06\/555-IMG_2778-Il-Padiglione-Venezia-La-Biennale-di-Venezia-\u00a9-Ph.-liberementi.jpg","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":4892,"url":"https:\/\/www.biancoscuro.it\/site\/biancoscuro-art-magazine-line-numero-20\/","url_meta":{"origin":17371,"position":0},"title":"BIANCOSCURO Art Magazine! On-line il nuovo numero #20","author":"Redazione BIANCOSCURO","date":"1 Febbraio 2017","format":false,"excerpt":"\"BIANCOSCURO\u00a0Rivista d'Arte\", sfoglia qui \u00a0sotto l'anteprima di BIANCOSCURO Art Magazine\u00a0#20 (febbraio-marzo 2017) o\u00a0scarica la versione integrale.\u00a0Iscriviti\u00a0alla nostra\u00a0mailing list\u00a0per essere costantemente aggiornato sui nostri eventi e sulle nostre attivit\u00e0:\u00a0inserisci\u00a0nome,\u00a0cognome\u00a0ed\u00a0e-mail\u00a0nei campi qui a destra per ricevere gratuitamente nella tua casella email. Ordina\u00a0su\u00a0artshop.biancoscuro.it Se vuoi puoi abbonarti alla versione\u00a0cartacea\u00a0cliccando sull'immagine qui sotto! Vuoi\u2026","rel":"","context":"In &quot;art magazine&quot;","block_context":{"text":"art magazine","link":"https:\/\/www.biancoscuro.it\/site\/category\/art-magazine\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2014\/03\/BAM_issue19_900px.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2014\/03\/BAM_issue19_900px.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2014\/03\/BAM_issue19_900px.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2014\/03\/BAM_issue19_900px.jpg?resize=700%2C400 2x"},"classes":[]},{"id":3661,"url":"https:\/\/www.biancoscuro.it\/site\/biancoscuro-leditoriale-dicembre-2015-gennaio-2016\/","url_meta":{"origin":17371,"position":1},"title":"BIANCOSCURO, l\u2019editoriale di dicembre 2015","author":"Vincenzo Chetta","date":"1 Dicembre 2015","format":false,"excerpt":"Rileggendo l\u2019editoriale del precedente numero di Biancoscuro, mi chiedevo se non fossi stato troppo duro, in fondo tutti possono sbagliare toni e modi, e magari noi eravamo solo incappati in un periodo di luna calante molto duro da superare... Poi per\u00f2 ho pensato ai due mesi trascorsi dalla sua stesura,\u2026","rel":"","context":"In &quot;art magazine&quot;","block_context":{"text":"art magazine","link":"https:\/\/www.biancoscuro.it\/site\/category\/art-magazine\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2014\/02\/blocco-partner-biancoscuro-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2014\/02\/blocco-partner-biancoscuro-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2014\/02\/blocco-partner-biancoscuro-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":3555,"url":"https:\/\/www.biancoscuro.it\/site\/biancoscuro-leditoriale-di-febbraio-ma-2015\/","url_meta":{"origin":17371,"position":2},"title":"BIANCOSCURO, L&#8217;editoriale di febbraio-marzo 2016","author":"Vincenzo Chetta","date":"1 Febbraio 2016","format":false,"excerpt":"Questo 2016 \u00e8 iniziato con i migliori auspici, tante nuove iniziative artistiche che promettono bene, per sopperire a quella mancanza di \u201coriginale modernit\u00e0\u201d che dovrebbe essere ormai la base per il rinnovamento delle formule pi\u00f9 consolidate, ma che rischiano di cadere, non tanto nel banale, quanto nel noioso. Se \u00e8\u2026","rel":"","context":"In &quot;art magazine&quot;","block_context":{"text":"art magazine","link":"https:\/\/www.biancoscuro.it\/site\/category\/art-magazine\/"},"img":{"alt_text":"\/\/\/ Berlin Art Week 2015 3 piani d\u2019Arte, dipinti, sculture, installazioni e videoinstallazioni","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/02\/aKEV_8252.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/02\/aKEV_8252.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/02\/aKEV_8252.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/02\/aKEV_8252.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":5584,"url":"https:\/\/www.biancoscuro.it\/site\/biancoscuro-leditoriale-giugno-luglio-2017\/","url_meta":{"origin":17371,"position":3},"title":"BIANCOSCURO, l\u2019editoriale di giugno-luglio 2017","author":"Vincenzo Chetta","date":"1 Giugno 2017","format":false,"excerpt":"Dopo un maggio ricco di eventi artistici, sui quali spicca l\u2019inaugurazione della 57.Biennale di Venezia (emozionante il Padiglione Italia che, finalmente dopo anni, ha riscosso grande successo da parte della critica. Avrebbe meritato il Leone d\u2019Oro, \u201csoffiato\u201d dalla Germania grazie al progetto di Anne Imhof), giugno e luglio si presentano\u2026","rel":"","context":"In &quot;art magazine&quot;","block_context":{"text":"art magazine","link":"https:\/\/www.biancoscuro.it\/site\/category\/art-magazine\/"},"img":{"alt_text":"Roberto Cuoghi - Imitazione di Cristo [Imitation of Christ] Padiglione Italia - 57. Esposizione Internazionale d\u2019Arte - La Biennale di Venezia","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2017\/05\/500cuoghitop.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":18318,"url":"https:\/\/www.biancoscuro.it\/site\/biancoscuro-leditoriale-di-vincenzo-chetta-69-aprile-maggio-2025\/","url_meta":{"origin":17371,"position":4},"title":"BIANCOSCURO #69, l\u2019editoriale di Vincenzo Chetta &#8211; APRILE\/MAGGIO 2025","author":"Vincenzo Chetta","date":"4 Aprile 2025","format":false,"excerpt":"Aprile si prospetta un mese intenso per il panorama artistico milanese, con una serie di eventi che attireranno l\u2019attenzione di appassionati e addetti ai lavori. Tra questi, spicca la Milano Art Week (MAW), che dal 1 al 6 aprile offrir\u00e0 oltre 200 appuntamenti.L\u2019evento di punta della MAW sar\u00e0, come di\u2026","rel":"","context":"In &quot;art magazine&quot;","block_context":{"text":"art magazine","link":"https:\/\/www.biancoscuro.it\/site\/category\/art-magazine\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/04\/MIART2023-999.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/04\/MIART2023-999.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/04\/MIART2023-999.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/04\/MIART2023-999.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":4714,"url":"https:\/\/www.biancoscuro.it\/site\/biancoscuro-leditoriale-dicembre16-gennaio17\/","url_meta":{"origin":17371,"position":5},"title":"BIANCOSCURO, l\u2019editoriale di dicembre&#8217;16-gennaio&#8217;17","author":"Vincenzo Chetta","date":"28 Novembre 2016","format":false,"excerpt":"L\u2019ultima uscita del 2016 di BIANCOSCURO: un altro anno \u00e8 gi\u00e0 passato, \u00e8 tempo di bilanci. Qualcuno sta per tirare le somme, qualcuno sta gi\u00e0 preparandosi per il 2017, noi di BIANCOSCURO stiamo facendo entrambe le cose, per ricordare il passato e guardare al futuro con fiducia. Fiducia nelle nostre\u2026","rel":"","context":"In &quot;art magazine&quot;","block_context":{"text":"art magazine","link":"https:\/\/www.biancoscuro.it\/site\/category\/art-magazine\/"},"img":{"alt_text":"Vincenzo Chetta Direttore Biancoscuro","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2015\/10\/firmaVincenzoChettaDirettoreBiancoscuro-300x103.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/17371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/users\/909"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/comments?post=17371"}],"version-history":[{"count":3,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/17371\/revisions"}],"predecessor-version":[{"id":17377,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/17371\/revisions\/17377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/media\/17376"}],"wp:attachment":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/media?parent=17371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/categories?post=17371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/tags?post=17371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}