{"id":19537,"date":"2026-05-13T16:53:03","date_gmt":"2026-05-13T14:53:03","guid":{"rendered":"https:\/\/www.biancoscuro.it\/site\/?p=19537"},"modified":"2026-05-13T16:53:05","modified_gmt":"2026-05-13T14:53:05","slug":"festival-del-tempo-short-film-2026","status":"publish","type":"post","link":"https:\/\/www.biancoscuro.it\/site\/festival-del-tempo-short-film-2026\/","title":{"rendered":"Festival del Tempo Short Film 2026"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">\u23f0 lettura <\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">min. <br><br><\/span><\/span>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/05\/Invito-2-1024x576.jpg\" alt=\"\" class=\"wp-image-19539\" srcset=\"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/05\/Invito-2-1024x576.jpg 1024w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/05\/Invito-2-300x169.jpg 300w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/05\/Invito-2-768x432.jpg 768w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/05\/Invito-2-1536x864.jpg 1536w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/05\/Invito-2-2048x1152.jpg 2048w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/05\/Invito-2-1320x743.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>Festival del Tempo &#8211; Settima edizione\u2028<\/strong><br \/><strong>SHORT ART ANIMATION DOCUMENTARY MUSIC FILM 2026<\/strong><br \/><strong>Dal 27 maggio al 30 giugno 2026 | Roma<\/strong><\/p>\n\n\n\n<p><strong>Arriva a Roma la settima edizione del FESTIVAL DEL TEMPO 2026, che si svolger\u00e0 dal 27 maggio al 30 giugno 2026. Ecco la SELEZIONE UFFICIALE DEI FILM IN CONCORSO e il CALENDARIO DELLE PROIEZIONI. \u2028<\/strong>\u2028<\/p>\n\n\n\n<p>Promosso dall\u2019Associazione culturale blowart e la direzione artistica di Roberta Melasecca, con il patrocinio della Regione Lazio, di Roma Capitale Assessorato alla Cultura e al Coordinamento delle iniziative riconducibili alla Giornata della Memoria, con la collaborazione del Municipio VII Roma Capitale.&nbsp;<\/p>\n\n\n\n<p>Dopo una attenta valutazione delle 2582 candidature pervenute da tutto il mondo tramite la piattaforma internazionale FilmFreeway, nelle diverse categorie &#8211; Short Film, Animazione, Film Sperimentale e Videoarte, Video Musicale, Documentario, Documentario lungo &#8211; la Direzione artistica ha selezionato 48 FILM che verranno proiettati durante il Festival. Saranno gli spettatori, insieme ad una Giuria tecnica, a valutare i film selezionati e ad attribuire i premi: di Miglior Film per Categoria, Miglior Attore e Miglior Attrice, Migliore Sceneggiatura, Premi della Giuria.&nbsp;<\/p>\n\n\n\n<p><strong>CALENDARIO<\/strong><\/p>\n\n\n\n<p><strong>27 MAGGIO 2026\u2028<\/strong>Studio Campo Boario Viale del Campo Boario 4A &#8211; Roma ore 18:00\u2028<br \/>Anteprima Festival del Tempo<br \/><strong>28 MAGGIO 2026<\/strong>\u2028Kou Gallery Via della Barchetta 13 &#8211; Roma ore 19:00\u2028<br \/><strong>29 MAGGIO 2026<\/strong>\u2028Studio Campo Boario Viale del Campo Boario 4A &#8211; Roma ore<br \/>18:00\u2028<br \/><strong>3 GIUGNO 2026<\/strong>\u2028Kou Gallery Via della Barchetta 13 &#8211; Roma ore 19:00<br \/><strong>4 GIUGNO 2026<\/strong>\u2028Kou Gallery Via della Barchetta 13 &#8211; Roma ore 19:00\u2028<br \/><strong>5 GIUGNO 2026<\/strong>\u2028AAIE Center for Contemporary Art Via Sermide 7 &#8211; Roma ore 18:30\u2028<br \/><strong>6 GIUGNO 2026\u2028<\/strong>Studio Campo Boario Viale del Campo Boario 4A &#8211; Roma ore 18:00<br \/><strong>10 GIUGNO 2026<\/strong>\u2028Logical Space Via dei S.S. Quattro 27 &#8211; Roma ore 18:30\u2028<br \/>SERATA DI GALA &#8211; PROIEZIONE VINCITORI<br \/><strong>26-27-28 GIUGNO 2026<\/strong>\u2028blowart contemporary space Via dei Savorelli 34a &#8211; Roma \u2028Conversazioni sui Film Selezionati dalle 18:00 alle 21:00\u2028<br \/>Inaugurazione spazio 26 giugno ore 18:00<\/p>\n\n\n\n<p><strong>PROGRAMMA<\/strong>: \u2028<a href=\"https:\/\/www.festivaldeltempo.it\/https:\/\/www.festivaldeltempo.it\/wp-content\/uploads\/2026\/04\/PROGRAMMA-FESTIVAL-DEL-TEMPO-2026.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.festivaldeltempo.it\/wp-content\/uploads\/2026\/04\/PROGRAMMA-FESTIVAL-DEL-TEMPO-2026.pdf<\/a><\/p>\n\n\n\n<p><strong>SELEZIONE UFFICIALE<\/strong><\/p>\n\n\n\n<p>Selezione Ufficiale SHORT FILM<\/p>\n\n\n\n<p>Alphabet di Dilek Milan Aktay &#8211; TURCHIA<br \/>Comodini di Kenta Cris\u00e0 &#8211; ITALIA\u2028Encore une belle journ\u00e9e di Charles Dutel &#8211; FRANCIA<br \/>First Snow di Jingjie Shen &#8211; CINA<br \/>Game Start di Jingru Zhao &#8211; CINA<br \/>Jusqu&#8217;au Prochain Souffle di Andrea Di Salvatore (nel cast Alessandro Haber) &#8211; ITALIA<br \/>Marusya di Anna Volkova &#8211; FEDERAZIONE RUSSA<br \/>Nereide di Alessandro D\u2019Ambrosi e Santa de Santis (nel cast Giulio Scarpati) &#8211; ITALIA<br \/>Non pi\u00f9 andrai di Raffaele Rossi &#8211; ITALIA<br \/>Qualcosa \u00e8 caduto dalla luna di Francesco Paolucci &#8211; ITALIA<br \/>Sei sempre stata tu di Sasha Alessandra Carlesi &#8211; ITALIA<br \/>Vegetalidade di Frederico Cordeiro Ferreira &#8211; PORTOGALLO<\/p>\n\n\n\n<p>Selezione Ufficiale FILM DI ANIMAZIONE<\/p>\n\n\n\n<p>A Certain Relationship di Yan Wang &#8211; AUSTRALIA<br \/>Ana Morphose di Joao Rodrigues &#8211; PORTOGALLO<br \/>Anemoia di Alessio Delfini &#8211; ITALIA<br \/>Down The Hatch di Alexandra Lukina &#8211; STATI UNITI<br \/>Drip di Zeynep Sude Yavuz &#8211; TURCHIA<br \/>Flower Bot di Elio Dubus, Margaux Hallot, Tiphaine Houdeau, Lo\u00efs Pastor, Marie Piazza, Cl\u00e9mence Thomire, Ludovic Vasse, Aur\u00e9lia Zerhouni &#8211; FRANCIA<br \/>La casa sul mare di Fulvio Davide Ricca &#8211; ITALIA<br \/>Motherhood di Maria Korporal &#8211; GERMANIA<br \/>Shelter di Chiara Vincenti Zakhia &#8211; ITALIA-LIBANO<br \/>There once a boy di Salma Waleed Enani &#8211; EGITTO<br \/>Tourist di Bob Verbruggen &#8211; BELGIO<br \/>Vera di minusLog Giustino Di Gregorio e Manuela Cappucci &#8211; ITALIA<br \/>What Remains di Yuto Yashiki &#8211; GIAPPONE<\/p>\n\n\n\n<p>Selezione Ufficiale FILM SPERIMENTALI E VIDEOARTE<\/p>\n\n\n\n<p>Dyptychos di Ana Barroso &#8211; PORTOGALLO<br \/>Expanded_memory di Lorenzo Papanti &#8211; ITALIA<br \/>Gap di Elena Muchnaya &#8211; FEDERAZIONE RUSSA<br \/>Materia alchemica di Luca Di Bartolo &#8211; ITALIA<br \/>Prima che arrivi AL di Simonetta Barbon &#8211; ITALIA<br \/>Sympoiesis di Ana Baer, Rocio Luna &#8211; MESSICO<br \/>Vulnerare di Sergio Mario Illuminato &#8211; ITALIA<\/p>\n\n\n\n<p>Selezione Ufficiale DOCUMENTARI LUNGHI<\/p>\n\n\n\n<p>Andrea prima di Paz &#8211; Appunti degli anni pescaresi di Peter Ranalli &#8211; ITALIA<br \/>Corpus et Vulnus di Sergio Mario Illuminato &#8211; ITALIA<br \/>Ensemble di Manuel Cundari, Eugenio Piluso &#8211; ITALIA<br \/>La luna sott\u2019acqua di Alessandro Negrini &#8211; ITALIA<br \/>La Poesia delle materie scartate di Manuel Canelles &#8211; ITALIA<\/p>\n\n\n\n<p>Selezione Ufficiale MUSIC VIDEO<\/p>\n\n\n\n<p>Army of the Lost di Martin Kukal &#8211; REPUBBLICA CECA<br \/>Che meraviglia di Sasha Alessandra Carlesi &#8211; ITALIA<br \/>Doomsday Valse di Luca Mauceri &#8211;&nbsp; ITALIA<br \/>Nadie Sabe di Danny Casas &#8211; CUBA<br \/>Turn My Love di Rosalie Loncin &#8211; FRANCIA<\/p>\n\n\n\n<p>Selezione Ufficiale DOCUMENTARI<\/p>\n\n\n\n<p>Chi siamo n\u00b01 &#8211; Mamma di Leonardo Casarolli &#8211; ITALIA<br \/>Davide, where are you? di Cecilia Rizzuto, Marco Pinnavaia &#8211; ITALIA<br \/>La mia parte di Emanuele Gabrieli, Antinea Radomska &#8211; ITALIA<br \/>Martyrion, storia di Isabelle di Luca Ciriello, Teresa Antignani &#8211; ITALIA-MALTA<br \/>Memoria di legno di Ambra Lupini &#8211; ITALIA<br \/>Teli di Girgenti di Giuseppe Galluzzo &#8211; ITALIA<\/p>\n\n\n\n<p>Il cinema, al Festival del Tempo, non spiega il tempo: lo fa sentire. Lo mette sulla pelle, lo fa pulsare, lo lascia entrare. Ogni opera diventa esperienza viva, presente, in evoluzione e in trasformazione.<\/p>\n\n\n\n<p>Il Festival del Tempo \u00e8 promosso dall\u2019associazione culturale blowart, con il patrocinio della Regione Lazio, di Roma Capitale_Assessorato alla Cultura e al Coordinamento delle iniziative riconducibili alla Giornata della Memoria, con il patrocinio di Cittadellarte Fondazione Pistoletto ONLUS, con la collaborazione del Municipio VII Roma Capitale, con la collaborazione di Kou Gallery, Studio Campo Boario, Logical Space, AAIE Center for Contemporary Art, Movimento VulnerarTe APS, con la media partnership di VulnerarTe Magazine, Quarta Parete Roma, Talkcity.it, The Parallel Vision, Unfolding Roma. L\u2019immagine guida della settima edizione del Festival del Tempo \u00e8 Costellazioni di Sara Ciuffetta per il Festival del Tempo 2024.<\/p>\n\n\n\n<p><strong>INFO<\/strong><\/p>\n\n\n\n<p><strong>Festival del Tempo\u2028<\/strong><br \/><strong>Associazione culturale blowart\u2028<\/strong><br \/><strong>Roberta Melasecca &#8211; Direttrice artistica<\/strong><br \/><strong>info@festivaldeltempo.it &#8211; tel. 3494945612\u2028<\/strong><br \/><strong>www.festivaldeltempo.it<\/strong><\/p>\n\n\n\n<p><strong>Ufficio Stampa<\/strong><br \/><strong>Roberta Melasecca Melasecca PressOffice &#8211; blowart<\/strong><br \/><strong>tel 3494945612 &#8211; roberta.melasecca@gmail.com &#8211; cartella stampa su www.melaseccapressoffice.it<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">\u23f0 lettura <\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">min. <\/p>\n<p><\/span><\/span>Festival del Tempo &#8211; Settima edizione\u2028SHORT ART ANIMATION DOCUMENTARY MUSIC FILM 2026Dal 27 maggio al 30 giugno 2026 | Roma Arriva a Roma la settima edizione del FESTIVAL DEL TEMPO 2026, che si svolger\u00e0 dal 27 maggio al 30 giugno 2026. Ecco la SELEZIONE UFFICIALE DEI FILM IN CONCORSO e il CALENDARIO DELLE PROIEZIONI. \u2028\u2028&hellip;&nbsp;<a href=\"https:\/\/www.biancoscuro.it\/site\/festival-del-tempo-short-film-2026\/\" rel=\"bookmark\">Leggi tutto &raquo;<span class=\"screen-reader-text\">Festival del Tempo Short Film 2026<\/span><\/a><\/p>\n","protected":false},"author":980,"featured_media":19539,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"footnotes":""},"categories":[5,1033,26,27],"tags":[],"class_list":["post-19537","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte","category-cinema","category-eventi","category-manifestazione"],"jetpack_featured_media_url":"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/05\/Invito-2.jpg","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":19376,"url":"https:\/\/www.biancoscuro.it\/site\/bando-xvii-land-art-al-furlo-chiamata-alle-arti\/","url_meta":{"origin":19537,"position":0},"title":"XVII Land Art al Furlo","author":"Roberta Melasecca","date":"19 Marzo 2026","format":false,"excerpt":"La Casa degli Artisti di Sant\u2019Anna lancia la chiamata \"Sguardi nel Parco\" per la XVII edizione della rassegna marchigiana. Si cercano opere alte almeno due metri e in grado di resistere al tempo e alle intemperie. Scadenza: 30 maggio. La Land Art cambia paradigma e, per la sua diciassettesima edizione,\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/03\/XVII-Land-art-al-furlo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/03\/XVII-Land-art-al-furlo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/03\/XVII-Land-art-al-furlo.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/03\/XVII-Land-art-al-furlo.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/03\/XVII-Land-art-al-furlo.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":5067,"url":"https:\/\/www.biancoscuro.it\/site\/piemonte-movie-glocal-film-festival-cinema-massimo\/","url_meta":{"origin":19537,"position":1},"title":"16\u00b0 PIEMONTE MOVIE gLocal Film Festival &#8211; Cinema Massimo","author":"Letizia Caspani","date":"10 Marzo 2017","format":false,"excerpt":"Venerd\u00ec 10 marzo \u00e8\u00a0la giornata\u00a0della\u00a016a gLocal Film Festival,\u00a0concentrata sulle sezioni competitive: SPAZIO PIEMONTE riservata ai cortometraggi e poi PANORAMICA DOC con ben quattro titoli in programma, di cui 2 anteprime assolute e 2 regionali.\u00a0Inoltre, aprono e chiudono questo terzo giorno di festival due appuntamenti realizzati in collaborazione con i principali\u2026","rel":"","context":"In &quot;concorso&quot;","block_context":{"text":"concorso","link":"https:\/\/www.biancoscuro.it\/site\/category\/concorso\/"},"img":{"alt_text":"Un altro me di Claudio Casazza","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2017\/03\/300UN-ALTRO-ME-di-Claudio-Casazza_1-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2017\/03\/300UN-ALTRO-ME-di-Claudio-Casazza_1-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2017\/03\/300UN-ALTRO-ME-di-Claudio-Casazza_1-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":19512,"url":"https:\/\/www.biancoscuro.it\/site\/presentazione-libro-cinque-storie-di-fotografia-e-psicoterapia-di-francesca-belgiojoso\/","url_meta":{"origin":19537,"position":2},"title":"Cinque storie di fotografia e psicoterapia","author":"Roberta Melasecca","date":"4 Maggio 2026","format":false,"excerpt":"Presentazione Libro Cinque storie di fotografia e psicoterapiadi Francesca Belgiojosoin conversazione con Floriana Di Giorgio Venerd\u00ec 8 maggio 2026 ore 18:00Galleria ZEMAVia Giulia 201 - Roma Venerd\u00ec 8 maggio 2026 alle ore 18.00, la Galleria Zema \u00e8 lieta di presentare il libro Cinque storie di fotografia e psicoterapia di Francesca\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/05\/invito.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/05\/invito.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/05\/invito.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/05\/invito.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/05\/invito.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":18269,"url":"https:\/\/www.biancoscuro.it\/site\/librinfestival-e-festival-del-tempo-2025-presentazione-i-libro-in-concorso\/","url_meta":{"origin":19537,"position":3},"title":"Librinfestival e Festival del Tempo","author":"Roberta Melasecca","date":"17 Marzo 2025","format":false,"excerpt":"Prende il via, il 28 marzo 2025, con la presentazione del primo libro in concorso, l\u2019edizione speciale 2025\u00a0di\u00a0LIBRINFESTIVAL, insieme al\u00a0FESTIVAL DEL TEMPO, promossa dall\u2019associazione Librinfestival, ISKRA\u00a0Cooperativa sociale onlusedall\u2019associazione\u00a0blowart e in occasione dei\u00a0dieci anni di LIBRINFESTIVAL.\u00a0 Infatti da marzo a novembre, gli eventi si articoleranno in modalit\u00e0 diffusa, intorno al tema\u2026","rel":"","context":"In &quot;concorso&quot;","block_context":{"text":"concorso","link":"https:\/\/www.biancoscuro.it\/site\/category\/concorso\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/03\/INVITO-Presentazioni-I-libro-Festival.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/03\/INVITO-Presentazioni-I-libro-Festival.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/03\/INVITO-Presentazioni-I-libro-Festival.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/03\/INVITO-Presentazioni-I-libro-Festival.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/03\/INVITO-Presentazioni-I-libro-Festival.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":19305,"url":"https:\/\/www.biancoscuro.it\/site\/decisione-imperfetta-performance-di-barbara-lalle\/","url_meta":{"origin":19537,"position":4},"title":"Memoria, colpa e patriarcato","author":"Roberta Melasecca","date":"18 Febbraio 2026","format":false,"excerpt":"Il dilemma dell\u2019archivio nella performance di Barbara Lalle al Forte Prenestino Nell'ambito del festival \"Witches Are Back 2026\", il Piazzale d'Armi del centro sociale romano ospita \"Decisione imperfetta\". Un'azione curata da Becchis, Marcenaro e Melasecca che interroga la violenza intrinseca nella trasmissione del sapere. Cosa fare dei documenti che hanno\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/02\/invito.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/02\/invito.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/02\/invito.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/02\/invito.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/02\/invito.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":19527,"url":"https:\/\/www.biancoscuro.it\/site\/geopolitica-trasformazioni-e-sviluppi-mostra-e-incontro\/","url_meta":{"origin":19537,"position":5},"title":"trasformazioni e sviluppi","author":"Roberta Melasecca","date":"12 Maggio 2026","format":false,"excerpt":"Gioved\u00ec 21 maggio 2026 alle ore 18:00, presso lo spazio Plus Arte Puls, si apre il nuovo ciclo di eventi Mutamenti e prospettive future con la mostra e l'incontro Geopolitica: trasformazioni e sviluppi, promosso dall\u2019Associazione culturalein tempo, a cura di Ida Mitrano e Rita Pedonesi. Il progetto intende proporre una\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/05\/9.-Giovannoni-Alessandra_-Verso-il-mare-2017-olio-su-tela-cm.110x150-copia.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/05\/9.-Giovannoni-Alessandra_-Verso-il-mare-2017-olio-su-tela-cm.110x150-copia.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/05\/9.-Giovannoni-Alessandra_-Verso-il-mare-2017-olio-su-tela-cm.110x150-copia.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/05\/9.-Giovannoni-Alessandra_-Verso-il-mare-2017-olio-su-tela-cm.110x150-copia.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2026\/05\/9.-Giovannoni-Alessandra_-Verso-il-mare-2017-olio-su-tela-cm.110x150-copia.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/19537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/users\/980"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/comments?post=19537"}],"version-history":[{"count":1,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/19537\/revisions"}],"predecessor-version":[{"id":19540,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/19537\/revisions\/19540"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/media\/19539"}],"wp:attachment":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/media?parent=19537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/categories?post=19537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/tags?post=19537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}