{"id":2361,"date":"2015-03-13T11:41:18","date_gmt":"2015-03-13T11:41:18","guid":{"rendered":"http:\/\/www.biancoscuro.it\/site\/?p=2361"},"modified":"2015-05-05T16:38:50","modified_gmt":"2015-05-05T16:38:50","slug":"andy-warhol-sul-como-opere-della-collezione-rosetta-barabino","status":"publish","type":"post","link":"https:\/\/www.biancoscuro.it\/site\/andy-warhol-sul-como-opere-della-collezione-rosetta-barabino\/","title":{"rendered":"Andy Warhol sul com\u00f2. Opere della Collezione Rosetta Barabino"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">\u23f0 lettura <\/span> <span class=\"rt-time\"> 2<\/span> <span class=\"rt-label rt-postfix\">min. <br><br><\/span><\/span><h3>ANDY WARHOL SUL COM\u00d2<br \/>\nOpere della Collezione Rosetta Barabino<\/h3>\n<p>Genova, Museo di arte Contemporanea di Villa Croce<br \/>\n2 aprile 2015 \u2013 5 luglio 2015<\/p>\n<p>Villa Croce ritorna a essere una dimora privata arredata con mobili di design per ospitare quasi cento opere da una straordinaria collezione genovese mai prima presentata in pubblico.\u00a0<strong>Le opere<\/strong>, scelte con cura e visionaria lungimiranza da Rosetta Barabino, <strong>sono il frutto di una passione condivisa con il figlio minore che per pi\u00f9 di trent\u2019anni li ha portati per gallerie e mostre d\u2019arte contemporanea.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-wysija-newsletters-max wp-image-2362 alignleft\" src=\"http:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2015\/03\/image003-600x400.jpg\" alt=\"ANDY WARHOL SUL COM\u00d2 - Opere della Collezione Rosetta Barabino (salotto) \" width=\"600\" height=\"400\" srcset=\"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2015\/03\/image003-600x400.jpg 600w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2015\/03\/image003-300x200.jpg 300w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2015\/03\/image003.jpg 646w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>La mostra riunisce settanta artisti italiani e internazionali, da <strong>Andy Warhol<\/strong> a <strong>Carl Andr\u00e8<\/strong>, da <strong>Donald Judd<\/strong> a <strong>Cy Twombly<\/strong>, da <strong>Dan Flavin<\/strong> a <strong>Robert Morris<\/strong>, oltre a <strong>Joseph Beuys<\/strong>, <strong>Olafur Eliasson<\/strong>, <strong>Cindy Sherman<\/strong>, <strong>Gordon Matta-Clark<\/strong>, <strong>Takashi Murakami<\/strong>, <strong>Ettore Spalletti<\/strong>, <strong>Ai Wei Wei<\/strong> , <strong>Fischli &amp; Weiss<\/strong> e <strong>Yang Fudong<\/strong> per <!--more-->raccontare la storia dell\u2019arte contemporanea attraverso lavori eccezionali che, installati in un ambiente domestico moderno e sofisticato, \u00a0dimostrano come l\u2019arte contemporanea possa diventare ispirazione quotidiana per immaginare il futuro.<\/p>\n<p>L\u2019esposizione vuole anche evidenziare come gi\u00e0 negli anni \u201860 e \u201870 la citt\u00e0 fosse il centro di un collezionismo illuminato e d&#8217;avanguardia che trovava nelle ricerche del Minimalismo americano il fulcro della contemporaneit\u00e0. Nelle parole di Gian Enzo Sperone, storico gallerista internazionale, e mentore della collezione: \u201cLa Signora Barabino, appartiene a quella ristretta \u00e9lite di visionari che nell\u2019ambito del collezionismo d\u2019avanguardia, dava a noi giovani mercanti l\u2019attenzione che era in tutti i sensi, l\u2019ossigenoper stare in vita.\u201d<\/p>\n<p>La mostra, <strong>promossa dal Comune di Genova e da Genova Palazzo Ducale<\/strong> &#8211; Fondazione per la Cultura in collaborazione con Civita, <strong>sar\u00e0 accompagnata da un catalogo edito da Marsilio<\/strong>, che offre la storia della collezione, immagini della mostra e testi critici di Ilaria Bonacossa, Francesco Bonami, Luca Cerizza oltre alle schede di tutte le opere in collezione.<\/p>\n<p>Orario mostra<br \/>\nda marted\u00ec a domenica, ore 11.00 &#8211; 19.00 (chiusura biglietteria ore 18.00)<\/p>\n<p>INFO<br \/>\ntel +39.010.580069<br \/>\nwww.villacroce.org<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">\u23f0 lettura <\/span> <span class=\"rt-time\"> 2<\/span> <span class=\"rt-label rt-postfix\">min. <\/p>\n<p><\/span><\/span>ANDY WARHOL SUL COM\u00d2 Opere della Collezione Rosetta Barabino Genova, Museo di arte Contemporanea di Villa Croce 2 aprile 2015 \u2013 5 luglio 2015 Villa Croce ritorna a essere una dimora privata arredata con mobili di design per ospitare quasi cento opere da una straordinaria collezione genovese mai prima presentata in pubblico.\u00a0Le opere, scelte con&hellip;&nbsp;<a href=\"https:\/\/www.biancoscuro.it\/site\/andy-warhol-sul-como-opere-della-collezione-rosetta-barabino\/\" rel=\"bookmark\">Leggi tutto &raquo;<span class=\"screen-reader-text\">Andy Warhol sul com\u00f2. Opere della Collezione Rosetta Barabino<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":2362,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"footnotes":""},"categories":[5,26],"tags":[],"class_list":["post-2361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte","category-eventi"],"jetpack_featured_media_url":"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2015\/03\/image003.jpg","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":4958,"url":"https:\/\/www.biancoscuro.it\/site\/artegenova-2017-ospitera-unesposizione-opere-scelte-andy-warhol\/","url_meta":{"origin":2361,"position":0},"title":"ArteGenova 2017 ospiter\u00e0 un&#8217;esposizione di opere scelte di Andy Warhol","author":"Redazione BIANCOSCURO","date":"15 Febbraio 2017","format":false,"excerpt":"Arte moderna e contemporanea nel padiglione Blu. Presente quest'anno un'esposizione di opere di Andy Warhol dalla collezione Falcioni Dal 17 al 20 febbraio con ArteGenova la citt\u00e0 ospita, per il tredicesimo anno consecutivo, nel padiglione Blu del quartiere fieristico, quattro giorni di mostre, eventi e presentazioni: un\u2019immersione totale nell\u2019arte moderna\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2017\/02\/KEV_0639.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2017\/02\/KEV_0639.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2017\/02\/KEV_0639.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":737,"url":"https:\/\/www.biancoscuro.it\/site\/andy-warhol-luomo-che-mori-due-volte-la-collezione-di-peter-brant-a-palazzo-reale\/","url_meta":{"origin":2361,"position":1},"title":"Andy Warhol. L\u2019uomo che mor\u00ec due volte. La collezione di Peter Brant a Palazzo Reale.","author":"Redazione BIANCOSCURO","date":"10 Febbraio 2014","format":false,"excerpt":"Ritornano a Milano le opere del padre della Pop Art americana:\u00a0Andy Warhol.\u00a0Warhol nacque in Pennsylvania il 6 agosto del 1928 da genitori immigrati dalla Slovacchia; da subito dimostr\u00f2 doti artistiche notevoli e studi\u00f2 arte pubblicitaria prima di trasferirsi a New York ed affermarsi come\u00a0grafico pubblicitario.\u00a0Nel 1952 la sua prima personale\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2014\/02\/Andy-Warhol-Blue-Shot-Marilyn-19641.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4421,"url":"https:\/\/www.biancoscuro.it\/site\/andy-warhol-inedito-le-prime-sperimentazioni-digitali-lamiga-1000\/","url_meta":{"origin":2361,"position":2},"title":"Andy Warhol inedito:  le prime sperimentazioni digitali con l&#8217;Amiga 1000","author":"Stefania Itolli","date":"20 Settembre 2016","format":false,"excerpt":"Dopo il successo riscontrato nell'autunno 2015 a Milano, le mostra \u201cAndy Warhol inedito: le prime sperimentazioni digitali con Amiga 1000\u201d, curata della galleria Deodato Arte, \u00e8 allestita dal MUSIL - Museo dell'industria e del lavoro di Rodengo Saiano (BS) fino al 30 ottobre. Dal 1\u00b0 ottobre, per ogni venerd\u00ec, sabato\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/09\/Andy-Warhol-Autoritratto-1985-digital-art.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/09\/Andy-Warhol-Autoritratto-1985-digital-art.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/09\/Andy-Warhol-Autoritratto-1985-digital-art.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/09\/Andy-Warhol-Autoritratto-1985-digital-art.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":13998,"url":"https:\/\/www.biancoscuro.it\/site\/andy-warhol-torna-a-milano-in-una-grande-mostra-alla-fabbrica-del-vapore\/","url_meta":{"origin":2361,"position":3},"title":"Andy Warhol a Milano","author":"Chiara","date":"2 Settembre 2022","format":false,"excerpt":"Warhol torna a Milano in una grande mostra alla Fabbrica del Vapore Dopo oltre 10 anni Andy Warhol torna in mostra a Milano, dal 22 ottobre al 26 marzo negli spazi della Fabbrica del Vapore. Con oltre\u00a0trecento opere divise in sette aree tematiche e tredici sezioni\u00a0- dagli inizi negli anni\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2022\/09\/69-Self-Portrait-Fright-Wig-ca.1986.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2022\/09\/69-Self-Portrait-Fright-Wig-ca.1986.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2022\/09\/69-Self-Portrait-Fright-Wig-ca.1986.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2022\/09\/69-Self-Portrait-Fright-Wig-ca.1986.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":15552,"url":"https:\/\/www.biancoscuro.it\/site\/prorogata-al-10-aprile-la-grande-mostra-su-andy-warhol-a-milano-oltre-60-000-i-visitatori\/","url_meta":{"origin":2361,"position":4},"title":"Prorogata al 10 aprile la grande mostra su Andy Warhol a Milano","author":"Chiara","date":"27 Febbraio 2023","format":false,"excerpt":"Oltre 60.000 i visitatori Con oltre\u00a0trecento opere divise in sette aree tematiche e tredici sezioni\u00a0la spettacolare mostra\u00a0Andy Warhol. La pubblicit\u00e0 della forma, in corso dal 22 ottobre 2022 a\u00a0Milano\u00a0alla\u00a0Fabbrica del Vapore, promossa e prodotta da\u00a0Comune\u00a0di Milano\u2013Cultura\u00a0e\u00a0Navigare, curata da\u00a0Achille Bonito Oliva\u00a0con\u00a0Edoardo Falcioni\u00a0per\u00a0Art Motors, Partner\u00a0BMW\u00a0eHublot, \u00e8 uno straordinario viaggio nell\u2019universo artistico e\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2023\/03\/WARHOL-Bonito-Oliva-e-Marilyn-nera.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2023\/03\/WARHOL-Bonito-Oliva-e-Marilyn-nera.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2023\/03\/WARHOL-Bonito-Oliva-e-Marilyn-nera.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2023\/03\/WARHOL-Bonito-Oliva-e-Marilyn-nera.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":4829,"url":"https:\/\/www.biancoscuro.it\/site\/pop-society-a-palazzo-ducale\/","url_meta":{"origin":2361,"position":5},"title":"Pop Society a Palazzo Ducale","author":"Redazione BIANCOSCURO","date":"3 Gennaio 2017","format":false,"excerpt":"Andy Warhol alle soglie della contemporaneit\u00e0 Genova ospita, negli spazi di Palazzo Ducale allestiti da Luca Beatrice, dal 21 ottobre al 26 febbraio, una grande retrospettiva dedicata al grande artista Andy Warhol, a trent\u2019anni esatti dalla sua scomparsa. Nato a Pittsurgh nel 1928 da immigrati dell\u2019Est europeo, arriva a New\u2026","rel":"","context":"In &quot;art magazine&quot;","block_context":{"text":"art magazine","link":"https:\/\/www.biancoscuro.it\/site\/category\/art-magazine\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2017\/01\/qaaa.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2017\/01\/qaaa.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2017\/01\/qaaa.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2017\/01\/qaaa.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/2361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/comments?post=2361"}],"version-history":[{"count":0,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/2361\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/media\/2362"}],"wp:attachment":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/media?parent=2361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/categories?post=2361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/tags?post=2361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}