{"id":4258,"date":"2016-07-22T17:36:45","date_gmt":"2016-07-22T17:36:45","guid":{"rendered":"http:\/\/www.biancoscuro.it\/site\/?p=4258"},"modified":"2016-07-22T17:36:45","modified_gmt":"2016-07-22T17:36:45","slug":"eremi-arte-percorsi-arte-natura-spiritualita","status":"publish","type":"post","link":"https:\/\/www.biancoscuro.it\/site\/eremi-arte-percorsi-arte-natura-spiritualita\/","title":{"rendered":"EREMI Arte &#8211; Percorsi tra Arte Natura Spiritualit\u00e0"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">\u23f0 lettura <\/span> <span class=\"rt-time\"> 4<\/span> <span class=\"rt-label rt-postfix\">min. <br><br><\/span><\/span><p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4259\" src=\"http:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/07\/invito-web-mail.jpg\" alt=\"invito-web mail\" width=\"620\" height=\"310\" srcset=\"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/07\/invito-web-mail.jpg 620w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/07\/invito-web-mail-300x150.jpg 300w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/07\/invito-web-mail-600x300.jpg 600w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p><strong>EREMI Arte &#8211; Percorsi tra Arte Natura Spiritualit\u00e0<\/strong><\/p>\n<p><strong>dal 30 luglio al 2 ottobre 2016<br \/>\n<\/strong><\/p>\n<p>Il giorno <strong>30 luglio 2016 alle ore 18<\/strong> presso l\u2019<em>Eremo di S. Spirito a Majella <\/em>\u2013 Roccamorice (PE) l&#8217;<strong>Accademia di Belle Arti de L&#8217;Aquila <\/strong>presenta <strong>EREMI Arte &#8211; Percorsi tra Arte Natura Spiritualit\u00e0<\/strong>, un progetto che <strong>dal 30 luglio fino al 2 ottobre 2016<\/strong> porter\u00e0 alla scoperta e valorizzazione degli eremi abruzzesi attraverso l\u2019<strong>arte contemporanea<\/strong>.<\/p>\n<p><strong>Enti promotori<\/strong> sono l\u2019<em>Accademia di Belle Arti de L\u2019Aquila<\/em>, la <em>Regione Abruzzo<\/em>, il <em>Parco Nazionale della Majella<\/em>, la <em>Fondazione CARISPAQ<\/em>, <strong>i<\/strong><strong>n collaborazione<\/strong> con i comuni di <em>Caporciano, Caramanico Terme, Roccamorice, Serramonacesca, Pretoro, Rapino, Palombaro, Lama dei Peligni, Palena, Pescocostanzo, Campo di Giove, Sulmona, Raiano, Villa Lago, Morino e Balsorano<\/em> <strong>e con<\/strong> <em>Italia Nostra<\/em>_Associazione Nazionale per la tutela del patrimonio storico, artistico e naturale della Nazione.<\/p>\n<p><strong>EREMI ARTE \u2013<\/strong> <strong>Percorsi tra Arte Natura Spiritualit\u00e0<\/strong> \u00e8 un ambizioso e articolato progetto nato all\u2019interno dell\u2019<strong>Accademia di Belle Arti dell\u2019Aquila<\/strong> realizzato con il sostegno della <strong>Fondazione Carispaq<\/strong>. Fortemente voluto dalla direzione dell\u2019Istituto, \u00e8 stato sviluppato da un gruppo di docenti, in collaborazione con gli enti locali, i Comuni, i Parchi, le Riserve Naturali e le associazioni del territorio interessato. EREMI Arte ha un\u2019idea fondante: mettere in relazione gli antichi eremi d\u2019Abruzzo con la cultura di oggi.<\/p>\n<p><em>\u201cQuell\u2019eredit\u00e0<\/em> <em>\u2013<\/em> <em>spirituale, storica, identitaria \u2013<\/em> <em>concretizzata in edifici di prestigio o in semplici grotte <\/em>\u2013 spiega il Direttore ABAQ <strong>Marco Brandizzi<\/strong> &#8211; <em>\u00e8<\/em> <em>valorizzata dal confronto con le pi\u00f9<\/em> <em>avanzate espressioni dell\u2019arte contemporanea. Con questo progetto l\u2019Accademia d\u00e0 il via a un percorso che avr\u00e0<\/em> <em>un suo proseguimento anche oltre le date fissate e pensiamo di portarlo avanti per tutto l\u2019anno di studi, cos\u00ec<\/em> <em>da mantenere alta l\u2019attenzione e il confronto su alcuni temi legati alla spiritualit\u00e0<\/em> <em>e al pensiero filosofico. L\u2019obiettivo del progetto \u2013<\/em> <em>nella ricorrenza del Giubileo Straordinario della Misericordia e della Perdonanza Celestiniana \u2013<\/em> <em>\u00e8<\/em> <em>far comprendere l\u2019importanza della conservazione e della valorizzazione degli eremi e come questi ultimi siano, ancora oggi, parte integrante della cultura delle popolazioni locali, nonch\u00e9<\/em> <em>patrimonio culturale e spirituale a livello globale\u201d.<\/em><\/p>\n<p>Oltre <strong>venti artisti<\/strong> di varia provenienza sono stati invitati a interpretare il \u201ccontesto eremo\u201d. Quindi la natura, gli spazi costruiti, la rete di relazioni, le tradizioni, tutti quegli aspetti che determinano l\u2019unicit\u00e0 di quei luoghi remoti ed evocativi. Non sono opere convenzionali, manufatti prodotti in atelier e poi trasportati in loco. Agli artisti \u00e8 stato richiesto di calarsi nell\u2019atmosfera degli eremi e realizzare appositamente un\u2019opera ispirata a questa esperienza. Sono, quindi, lavori a carattere temporaneo, ma in alcuni casi anche pensati per rimanere sul posto. Nel pieno rispetto dello spirito dell\u2019iniziativa, ogni opera diventa una sorta di viatico verso una forma di meditazione nata, s\u00ec, dalle suggestioni del paesaggio, ma aggiornata alle tensioni del mondo di oggi.<\/p>\n<p>Ma non solo. <strong>EREMI <\/strong>\u00e8 anche l\u2019occasione per dimostrare a una platea internazionale il ruolo cardine che l\u2019Accademia aquilana ricopre come piattaforma di produzione, scambio e diffusione di stimoli culturali, perch\u00e9 questo progetto coinvolge tutte le professionalit\u00e0, le competenze e le capacit\u00e0 dei suoi docenti oltre all\u2019entusiasmo e la voglia di fare dei propri studenti. L\u2019idea \u00e8 quella di proporsi come un vero \u201cincubatore\u201d di creativit\u00e0 e conoscenza capace di fare rete, educare e coinvolgere studenti, territorio, studiosi e professionisti esterni. Parte essenziale del progetto, infatti, sar\u00e0 un <strong>simposio internazionale<\/strong> dove filosofi, teologi, artisti e intellettuali saranno chiamati a dare il proprio contributo sul tema cardine dell\u2019intero progetto: la rilettura degli eremi abruzzesi nella contemporaneit\u00e0. Gli atti del simposio saranno poi oggetto di una successiva pubblicazione.<\/p>\n<p><em>\u201cEREMI ARTE \u2013<\/em> <em>Percorsi tra Arte Natura Spiritualit\u00e0<\/em> \u2013 conclude il Presidente dell\u2019Accademia di Belle Arti <strong>Roberto Marotta<\/strong> &#8211; <em>si propone di diventare uno strumento di valorizzazione delle risorse locali \u2013<\/em> <em>storiche, paesaggistiche, formative \u2013<\/em> <em>mediante la produzione culturale e non solo lo sfruttamento dei giacimenti turistici esistenti. Dunque, un nuovo modo di fare promozione anche turistica di un territorio dalla bellezza mozzafiato e spesso, ancora oggi, sconosciuto\u201d.<\/em><\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4260\" src=\"http:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/07\/Mappa-Eremi-con-artisti-2-Copia.jpg\" alt=\"Mappa-Eremi-con-artisti 2 - Copia\" width=\"620\" height=\"438\" srcset=\"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/07\/Mappa-Eremi-con-artisti-2-Copia.jpg 620w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/07\/Mappa-Eremi-con-artisti-2-Copia-300x212.jpg 300w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/07\/Mappa-Eremi-con-artisti-2-Copia-600x424.jpg 600w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p><strong>EREMI_ARTISTI<\/strong><u><br \/>\n<\/u><\/p>\n<p>BALSORANO &#8211; Grotta Sant&#8217;Angelo<strong>: Pierluigi Calignano<\/strong><br \/>\nCAMPO DI GIOVE &#8211; Madonna di Coccia: <strong>Emanuela Barbi<\/strong><br \/>\nCAPORCIANO &#8211; San Michele di Bominaco: <strong>Enzo Umbaca<\/strong><br \/>\nCARAMANICO TERME &#8211; S. Onofrio all&#8217;Orfento: <strong>Federico Fusi<\/strong><br \/>\nCARAMANICO TERME &#8211; S. Giovanni all&#8217;Orfento: <strong>Calixto Ramirez Correa<\/strong><br \/>\nLAMA DEI PELIGNI &#8211; Grotta Sant&#8217;Angelo: <strong>Romano Bertuzzi<\/strong><br \/>\nMORINO &#8211; Madonna del Cauto: <strong>Elena Mazzi<\/strong><br \/>\nPALENA- Madonna dell&#8217;Altare: <strong>Rossano Polidoro e Marco Marzuoli<\/strong><br \/>\nPALOMBARO &#8211; Grotta San&#8217;Angelo: <strong>Aurelien Mauplot<\/strong><br \/>\nPESCOCOSTANZO &#8211; San Michele: <strong>Marco Bernardi<\/strong><br \/>\nPRETORO &#8211; Madonna della Mazza: <strong>Maria Chiara Calvani<\/strong><br \/>\nPRETORO &#8211; Grotta dell&#8217;Eremita: <strong>Maria Chiara Calvani<\/strong><br \/>\nRAIANO &#8211; Eremo San Venanzio: <strong>Federico Cavallini<\/strong><br \/>\nRAPINO &#8211; Grotta del colle: <strong>Chiara Camoni e Luca Bertolo<\/strong><br \/>\nROCCAMORICE \u2013 S. Spirito a Majella: <strong>Aldo Grazzi e William Basinski<\/strong><br \/>\nROCCAMORICE &#8211; S. Bartolomeo in Legio: <strong>Zaelia Bishop<\/strong><br \/>\nSERRAMONACESCA &#8211; S. Liberatore a Maiella (abbazia): <strong>Alterazioni Video<\/strong><br \/>\nSERRAMONACESCA &#8211; S. Onofrio: <strong>Elena Bellantoni<\/strong><br \/>\nSULMONA &#8211; S. Onofrio al Morrone: <strong>Giuseppe Stampone<\/strong><br \/>\nSULMONA &#8211; Sant&#8217;Angelo in Vetuli: <strong>Franco Menicagli<\/strong><br \/>\nVILLA LAGO &#8211; Grotta di San Domenico: <strong>Matteo Fato<\/strong><\/p>\n<p><strong>INFO<\/strong><\/p>\n<p><strong>Eremi Arte \u2013<\/strong> <strong>Percorsi tra arte natura spiritualit\u00e0<\/strong><\/p>\n<p><strong>Artisti:<\/strong> <em>Alterazioni Video, Emanuela Barbi, William Basinski, Elena Bellantoni, Marco Bernardi, Romano Bertuzzi, Zaelia Bishop, Pierluigi Calignano, Chiara Camoni e Luca Bertolo, Federico Cavallini, Maria Chiara Calvani,\u00a0 Matteo Fato, Federico Fusi, Elena Mazzi, Franco Menicagli, Rossano Polidoro e Marco Marzuoli, Aurelien Mauplot, Calixto Ramirez Correa, Giuseppe Stampone, Enzo Umbaca<\/em><\/p>\n<p><strong>Curatori: <\/strong><em>Maurizio Coccia, Enzo De Leonibus, Silvano Manganaro<\/em><\/p>\n<p><strong>Inaugurazione:<\/strong> <strong>sabato 30 luglio 2016 ore 18.00 <\/strong><\/p>\n<p><strong>Santo Spirito a Maiella | <\/strong><strong>Strada Provinciale 22<\/strong><strong> \u2013 Roccamorice (PE)<\/strong><\/p>\n<p><strong>Dal<\/strong> <strong>30 luglio al<\/strong> <strong>2 ottobre 2016<\/strong><\/p>\n<p><strong>Ingresso:<\/strong> gratuito (ad esclusione del complesso di S. Spirito a <strong>Maiella)<\/strong><\/p>\n<p><strong>Orari: <\/strong>variabili (in base alla disponibilit\u00e0 dei singoli eremi)<\/p>\n<p><strong>www.accademiabellearti.laquila.it<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ufficio stampa: Angela Ciano <\/strong><strong>\u2013 <\/strong><strong>ufficio<\/strong><a href=\"mailto:stampa@accademiabellearti.laquila.it\"><strong>stampa@accademiabellearti.laquila.it<\/strong><\/a><strong>; <\/strong><a href=\"mailto:cianoa10@gmail.com\"><strong>cianoa10@gmail.com<\/strong><\/a><strong>;<\/strong><strong> +393483402130<br \/>\n<\/strong><\/p>\n<p><strong>Web Communication: Roberta Melasecca; + 39 349.4945612; roberta.melasecca@gmail.com<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">\u23f0 lettura <\/span> <span class=\"rt-time\"> 4<\/span> <span class=\"rt-label rt-postfix\">min. <\/p>\n<p><\/span><\/span>EREMI Arte &#8211; Percorsi tra Arte Natura Spiritualit\u00e0 dal 30 luglio al 2 ottobre 2016 Il giorno 30 luglio 2016 alle ore 18 presso l\u2019Eremo di S. Spirito a Majella \u2013 Roccamorice (PE) l&#8217;Accademia di Belle Arti de L&#8217;Aquila presenta EREMI Arte &#8211; Percorsi tra Arte Natura Spiritualit\u00e0, un progetto che dal 30 luglio fino&hellip;&nbsp;<a href=\"https:\/\/www.biancoscuro.it\/site\/eremi-arte-percorsi-arte-natura-spiritualita\/\" rel=\"bookmark\">Leggi tutto &raquo;<span class=\"screen-reader-text\">EREMI Arte &#8211; Percorsi tra Arte Natura Spiritualit\u00e0<\/span><\/a><\/p>\n","protected":false},"author":980,"featured_media":4259,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"footnotes":""},"categories":[5,26,27,24],"tags":[751],"class_list":["post-4258","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte","category-eventi","category-manifestazione","category-mostre","tag-accademia-belle-arti-laquila"],"jetpack_featured_media_url":"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/07\/invito-web-mail.jpg","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":5688,"url":"https:\/\/www.biancoscuro.it\/site\/eremi-arte-2017_percorsi-arte-natura-spiritualita\/","url_meta":{"origin":4258,"position":0},"title":"Eremi Arte 2017 &#8211; Percorsi tra arte natura spiritualit\u00e0","author":"Roberta Melasecca","date":"14 Luglio 2017","format":false,"excerpt":"\u00a0 Eremi Arte 2017_Percorsi tra arte natura spiritualit\u00e0 Valorizzazione degli Eremi abruzzesi attraverso l\u2019arte contemporanea Inaugurazione 15 luglio ore 10.30 Abbazia di Santo Spirito al Morrone - Badia Sulmona\u00a0 Il progetto, giunto alla sua seconda edizione, \u00e8 volto alla riscoperta dei luoghi storici legati alla spiritualit\u00e0 dei romitaggi dell\u2019Appennino centrale\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2017\/07\/invito-inaugurazione-web1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2017\/07\/invito-inaugurazione-web1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2017\/07\/invito-inaugurazione-web1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":5513,"url":"https:\/\/www.biancoscuro.it\/site\/variazioni-sulla-durata-24-ore-performance-incontri-pubblico\/","url_meta":{"origin":4258,"position":1},"title":"VARIAZIONI SULLA DURATA \/ 24 ore di performance e di incontri con il pubblico","author":"Roberta Melasecca","date":"15 Maggio 2017","format":false,"excerpt":"VARIAZIONI SULLA DURATA \/ 24 ore di performance e di incontri con il pubblico A cura di Maurizio Coccia 18 maggio 2017 dalle ore 20.00 | Spazio VARCO | L\u2019Aquila Fino alle ore 20.00 del 19 maggio 2017 Il 18 maggio 2017 alle ore 20.00, presso Spazio VARCO a L\u2019Aquila,\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2017\/05\/VARIAZIONI-SULLA-DURATA-web-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2017\/05\/VARIAZIONI-SULLA-DURATA-web-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2017\/05\/VARIAZIONI-SULLA-DURATA-web-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":8528,"url":"https:\/\/www.biancoscuro.it\/site\/latelier-di-giuliana-silvestrini\/","url_meta":{"origin":4258,"position":2},"title":"L\u2019Atelier di Giuliana Silvestrini","author":"Roberta Melasecca","date":"15 Gennaio 2019","format":false,"excerpt":"L\u2019Atelier di Giuliana Silvestrini Mostra personale Via Fabio Filzi 40 \u2013 presso La Piazza del Duomo Monterotondo (RM) Dal 19 al 20 gennaio 2019 Giuliana Silvestrini apre il suo Atelier nel centro storico di Monterotondo, in via Fabio Filzi 40, con una personale che rappresenta la sintesi del suo percorso\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2019\/01\/met-in-giallo-part.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2019\/01\/met-in-giallo-part.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2019\/01\/met-in-giallo-part.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2019\/01\/met-in-giallo-part.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2019\/01\/met-in-giallo-part.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":17955,"url":"https:\/\/www.biancoscuro.it\/site\/larte-come-ponte-generazionale-la-collaborazione-tra-laccademia-di-belle-arti-di-roma-e-la-mostra-iosonovulnerabile-di-sergio-mario-illuminato\/","url_meta":{"origin":4258,"position":3},"title":"L\u2019arte come ponte generazionale","author":"Roberta Melasecca","date":"28 Dicembre 2024","format":false,"excerpt":"La collaborazione tra l\u2019Accademia di Belle Arti di Roma e la mostra iosonovulnerabile di Sergio Mario Illuminato Michele Vasca La mostra iosonovulnerabile di Sergio Mario Illuminato rappresenta un esempio di come l\u2019arte contemporanea possa fungere da catalizzatore per il dialogo tra generazioni, culture e discipline. Questo progetto transdisciplinare, che ha\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2024\/12\/Michele-Vasca-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2024\/12\/Michele-Vasca-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2024\/12\/Michele-Vasca-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2024\/12\/Michele-Vasca-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":3748,"url":"https:\/\/www.biancoscuro.it\/site\/flow-flew-flaw-giovanni-paolo-fedele\/","url_meta":{"origin":4258,"position":4},"title":"\u201cflow. flew. flaw.\u201d di Giovanni Paolo Fedele","author":"Roberta Melasecca","date":"20 Aprile 2016","format":false,"excerpt":"\u201cflow. flew. flaw.\u201d di Giovanni Paolo Fedele a cura di Alberta Romano Il giorno 30 aprile 2016 alle ore 18.00, presso Spazio VARCO a L'Aquila, inaugura flow. flew. flaw. prima mostra personale di Giovanni Paolo Fedele a cura di Alberta Romano. Dopo una ricerca durata oltre un anno e mezzo,\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/04\/immagine.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/04\/immagine.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/04\/immagine.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/04\/immagine.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":12247,"url":"https:\/\/www.biancoscuro.it\/site\/laquila-dei-sogni-installazione-di-ernesto-pugliese\/","url_meta":{"origin":4258,"position":5},"title":"L&#8217;Aquila dei sogni &#8211; Installazione di Ernesto Pugliese","author":"Roberta Melasecca","date":"19 Agosto 2021","format":false,"excerpt":"Il giorno 26 agosto 2021 alle ore 20.00, durante i giorni della Perdonanza Celestiniana, Ernesto Pugliese presenta l\u2019installazione L\u2019Aquila dei sogni, presso il Cortile di Palazzo Ciolina, nel cuore del centro storico de L\u2019Aquila.\u00a0 Tornare a L\u2019Aquila dopo un decennio, ripercorrendo i luoghi degli anni di studi universitari in una\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/08\/copertina-fb2-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/08\/copertina-fb2-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/08\/copertina-fb2-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/08\/copertina-fb2-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/08\/copertina-fb2-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/08\/copertina-fb2-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/4258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/users\/980"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/comments?post=4258"}],"version-history":[{"count":0,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/4258\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/media\/4259"}],"wp:attachment":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/media?parent=4258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/categories?post=4258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/tags?post=4258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}