{"id":4493,"date":"2016-09-29T17:13:38","date_gmt":"2016-09-29T17:13:38","guid":{"rendered":"http:\/\/www.biancoscuro.it\/site\/?p=4493"},"modified":"2016-09-29T17:13:38","modified_gmt":"2016-09-29T17:13:38","slug":"premio-internazionale-architettura-sacra-pavia","status":"publish","type":"post","link":"https:\/\/www.biancoscuro.it\/site\/premio-internazionale-architettura-sacra-pavia\/","title":{"rendered":"Premio Internazionale di Architettura Sacra &#8211; Pavia"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">\u23f0 lettura <\/span> <span class=\"rt-time\"> 7<\/span> <span class=\"rt-label rt-postfix\">min. <br><br><\/span><\/span><h4>Fondazione Frate Sole<br \/>\nGiornata di premiazione &#8211; marted\u00ec 4 ottobre<br \/>\nPremio Internazionale di Architettura Sacra<br \/>\nVI edizione &#8211; 2016 &#8211;\u00a0Pavia<\/h4>\n<p>In occasione della festivit\u00e0 di San Francesco d&#8217;Assisi, <b>marted\u00ec 4 ottobre<\/b> si svolger\u00e0 <b>a Pavia la Giornata di premiazione per la VI edizione del Premio Internazionale di Architettura <span class=\"il\">Sacra<\/span><\/b>, un&#8217;occasione per riflettere sul dibattito contemporaneo intorno ai temi dell&#8217;architettura <span class=\"il\">sacra<\/span> e a quelli riguardanti le prospettive pi\u00f9 avanzate.<\/p>\n<p>Durante la Giornata, si <b>premieranno i primi tre progetti<\/b> classificati, s&#8217;inaugurer\u00e0 la <b>mostra<\/b>\u00a0che racconta tutti gli 86 progetti partecipanti, e si potr\u00e0 assistere alla <b>Conversazione pavese<\/b> del vincitore, l&#8217;architetto spagnolo Rafael Moneo.<\/p>\n<p><i>Grati e testimoni del fervore artistico che sempre ha accompagnato la missione di Padre Costantino Ruggeri<\/i> &#8211; dichiara l&#8217;architetto Luigi Leoni, Presidente della Fondazione Frate Sole e stretto collaboratore di Padre Costantino &#8211; , r<i>accogliendo la sua preziosa eredit\u00e0 siamo lieti di essere stati chiamati a promuovere nel mondo l&#8217;interesse, lo studio e la ricerca nel campo dell&#8217;architettura <span class=\"il\">sacra<\/span>. Siamo consapevoli che l&#8217;impegno \u00e8 arduo, non privo di difficolt\u00e0, ma certamente affascinante e stimolante, ricco di prospettive future esaltanti per le implicazioni che l&#8217;architettura <span class=\"il\">sacra<\/span> offre nel proclamare a gran voce alti valori spirituali, i soli capaci di toccare la mente e soprattutto il cuore dell&#8217;uomo per elevarlo e farlo vivere nella speranza, nella pace e nella verit\u00e0. Matrice di verit\u00e0 \u00e8 la bellezza, di cui padre Costantino \u00e8 stato cantore, ricercata con creativit\u00e0, affinch\u00e9, mai paghi dei risultati raggiunti, si sia sempre tesi a superare i confini del nostro mondo per raggiungere nuovi orizzonti che diano innumerevoli ispirazioni e luci, in consonanza con le risposte da donare all&#8217;uomo contemporaneo in cerca di un profondo senso del suo divenire nella storia. La creativit\u00e0 e la purezza sono segni che, nella novit\u00e0 dei linguaggi artistici, contraddistinguono l&#8217;anelito che la Fondazione Frate Sole vuole testimoniare con forza per sollecitare gli operatori nel campo dell&#8217;architettura <span class=\"il\">sacra<\/span> a farsi paladini di autenticit\u00e0 e di luce.<\/i><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4496\" src=\"http:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/09\/St-Trinitatis.jpg\" alt=\"st-trinitatis\" width=\"1086\" height=\"768\" srcset=\"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/09\/St-Trinitatis.jpg 1086w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/09\/St-Trinitatis-300x212.jpg 300w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/09\/St-Trinitatis-768x543.jpg 768w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/09\/St-Trinitatis-1024x724.jpg 1024w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/09\/St-Trinitatis-600x424.jpg 600w\" sizes=\"auto, (max-width: 1086px) 100vw, 1086px\" \/><\/p>\n<p><i>\u00c8 un grande onore ospitare per le Conversazioni Pavesi un architetto di fama internazionale come Rafael Moneo, Pritzker Prize nel 1996 e vincitore della VI edizione del Premio Internazionale di Architettura <span class=\"il\">Sacra<\/span>, organizzato dalla Fondazione Frate Sole di Pavia, e rivolto ai nuovi edifici religiosi di culto cristiano realizzati in tutto il mondo. La sua Chiesa di Iesu, a San Sebastian (in Spagna), dalle forme pulite e compatte, ha conquistato la Giuria, che all&#8217;unanimit\u00e0 ha deciso di assegnarle il primo premio. L&#8217;architetto, presente a Pavia per ritirare il premio e ospite della Fondazione Frate Sole, che ringrazio, concluder\u00e0 la cerimonia di premiazione dialogando nella suggestiva Sala degli Affreschi del Collegio Borromeo con Susanna Zatti, direttrice dei Musei Civici del Castello Visconteo di Pavia, in un confronto informale intorno al tema dell&#8217;architettura contemporanea,<\/i> dichiara Giacomo Galazzo, Assessore alla Cultura del Comune di Pavia. <i><br \/>\n<\/i><br \/>\nLa Giornata <b>si aprir\u00e0 alle ore 12<\/b> nel <b>cortile di Palazzo Broletto<\/b> con l&#8217;inaugurazione della <b>mostra documentaria<\/b> <i><b>2016 &#8211; Premio Internazionale di Architettura <span class=\"il\">Sacra<\/span> &#8211; chiese partecipanti e indirizzi di progetto<\/b><\/i>, che raccoglie tutti gli 86 progetti che hanno partecipato alla VI edizione del Premio, allestiti grazie a una struttura autoportante sotto il porticato, e visibili al pubblico fino all&#8217;11 ottobre.<br \/>\nPer ciascun progetto sono presentate in mostra le immagini degli spazi esterni e degli spazi interni, e accanto si trovano i disegni tecnici, che illustrano con rigore scientifico la realizzazione delle diverse architetture, cos\u00ec da renderle comprensibili non solo agli addetti ai lavori, ma anche al grande pubblico. Nel percorso \u00e8 esposta anche la maquette realizzata dal vincitore, lo spagnolo Rafael Moneo. Il modellino della Chiesa di Iesu, a San Sebastian, sar\u00e0 successivamente donato alla Fondazione Frate Sole.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4495\" src=\"http:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/09\/Moneo-3.jpg\" alt=\"moneo-3\" width=\"1148\" height=\"768\" srcset=\"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/09\/Moneo-3.jpg 1148w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/09\/Moneo-3-300x201.jpg 300w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/09\/Moneo-3-768x514.jpg 768w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/09\/Moneo-3-1024x685.jpg 1024w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/09\/Moneo-3-600x401.jpg 600w\" sizes=\"auto, (max-width: 1148px) 100vw, 1148px\" \/><\/p>\n<p>La <b>cerimonia ufficiale di premiazione<\/b>, moderata dal celebre storico dell&#8217;architettura Francesco Dal Co, avr\u00e0 inizio <b>alle ore 15<\/b> nella <b>Sala degli Affreschi del Collegio Borromeo di Pavia<\/b>, con un momento istituzionale e gli interventi delle autorit\u00e0 cittadine. Seguir\u00e0 l&#8217;assegnazione dei premi &#8211; alla presenza dell&#8217;architetto cileno Cristian Undurraga, vincitore, con la &#8220;Capilla del Retiro&#8221;, della passata edizione del Premio &#8211; durante la quale ciascun finalista racconter\u00e0 al pubblico il proprio progetto.<br \/>\nSi comincer\u00e0 con le menzioni speciali (la Cappella St. John the Baptist, realizzata nel quartiere berlinese di Johannisthal dallo studio tedesco di architettura Br\u00fcckner &amp;\u00a0 Br\u00fcckner e la Cappella Saint John Baptist, ideata dall&#8217;architetto spagnolo Alejandro Beautell, a Tenerife, nelle Canarie) a cui verr\u00e0 consegnata una targa realizzata dalla Fondazione Frate Sole. Si proseguir\u00e0 con lo studio tedesco di architettura Schulz und Schulz, che si \u00e8 aggiudicato il terzo posto con la nuova Chiesa St. Trinitatis, nella citt\u00e0 di Lipsia (Germania), e che ricever\u00e0 un contributo in denaro pari a 5.000 euro. Agli architetti Thu Huong Thi Vu e Tuan Dung Nguyen, secondi classificati con la Chiesa Nuova della Parrocchia di KaDon, a Don Duong, nella Provincia di Lam Dong, in Vietnam, saranno assegnati 10.000 euro. Rafael Moneo, primo classificato con la Chiesa di Iesu, a San Sebastian, verr\u00e0 introdotto dallo storico dell&#8217;architettura Francesco Dal Co, e ricever\u00e0 un contributo in denaro pari a 15.000 euro e l&#8217;ormai celebre &#8220;Cieldoro&#8221;, ovvero la riproduzione in acciaio lucido di una scultura realizzata da Padre Costantino in occasione della prima edizione del Premio Internazionale di Architettura <span class=\"il\">Sacra<\/span> (1996).<\/p>\n<p>In occasione della cerimonia di premiazione, sar\u00e0 anche pubblicato un <b>catalogo scientifico<\/b> inerente ai progetti della VI edizione del Premio Internazionale di Architettura <span class=\"il\">Sacra<\/span>. Nel catalogo sono raccolte le immagini, i disegni, le relazioni tecniche dei tre progetti vincitori e delle due menzioni, oltre alle motivazioni della Giuria, alle biografie degli architetti e a una piccola parte riservata agli altri partecipanti dell&#8217;edizione 2016.<\/p>\n<p>Il Premio Internazionale di Architettura <span class=\"il\">Sacra<\/span> \u00e8 organizzato dalla Fondazione Frate Sole, e patrocinato da Enti locali e Istituti nazionali ecclesiastici e culturali come la Pontificia Commissione per i Beni Culturali Ecclesiastici della Santa Sede, il Ministero per i Beni e le Attivit\u00e0 culturali, il Consiglio Nazionale degli Architetti, l&#8217;Ordine degli Architetti Pianificatori Paesaggisti della Provincia di Pavia, la Diocesi di Pavia, il Comune di\u00a0 Pavia, l&#8217;Universit\u00e0 degli Studi di Pavia, l&#8217;Ufficio Nazionale dell&#8217;Edilizia di Culto, la Provincia S. Antonio dei Frati Minori.<\/p>\n<h3>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4497\" src=\"http:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/09\/Vietnam-2.jpg\" alt=\"vietnam-2\" width=\"1086\" height=\"768\" srcset=\"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/09\/Vietnam-2.jpg 1086w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/09\/Vietnam-2-300x212.jpg 300w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/09\/Vietnam-2-768x543.jpg 768w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/09\/Vietnam-2-1024x724.jpg 1024w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/09\/Vietnam-2-600x424.jpg 600w\" sizes=\"auto, (max-width: 1086px) 100vw, 1086px\" \/><br \/>\nInternational Award for Sacred Architecture<br \/>\nFrate Sole Foundation<br \/>\nPrize-giving Day \u2013 Tuesday, October 4th<br \/>\n6th Edition &#8211; 2016 &#8211; \u00a0Pavia<\/h3>\n<p>On the occasion of the feast of St. Francis of Assisi, on <b>Tuesday, October 4<sup>th<\/sup><\/b>, the <b>Prize-giving Day<\/b> for the <b>4<sup>th<\/sup> edition of the International Award for Sacred Architecture<\/b> will be held in Pavia; it will be an opportunity to reflect on the contemporary debate around the themes of sacred architecture and those regarding the most advanced prospects, subjects much cherished by Father Constantine, the founder of the Award, who was himself an artist projected towards the future and constantly on the move to approach novelty.<\/p>\n<p>During the Day, which will be open free to the general public, prizes will be awarded to the top three contestants\u2019 plans, as well as opening a documentary exhibition that provides a description of all the 86 participating projects. Moreover, those present will have the opportunity to attend the talk of the winner, the Spanish architect Rafael Moneo, as part of the event \u201cConversazioni Pavesi\u201d (\u201cPavian Talks\u201d).<\/p>\n<p><i>Grateful witnesses of the artistic fervour than has always accompanied the mission of Father <\/i><i>Costantino Ruggeri<\/i> \u2013 claims architect Luigi Leoni, President of the Frate Sole Foundation and close collaborator of Father Costantino \u2013, <i>resuming his precious heritage, we are delighted to have been called to promote around the world the interest, study and research in the field of sacred architecture. We are aware that this is a dainty commitment, not without difficulties, though definitely fascinating and challenging, full of exciting prospects for the future owing to the implications entailed by sacred architecture in proclaiming loudly high spiritual values, the only ones capable of touching man\u2019s mind and &#8211; above all &#8211; heart to raise him and cause him to live in hope, peace and truth. The matrix of truth is beauty, so deeply celebrated by Father Costantino, sought with creativeness so that, never satisfied with the results achieved, we are constantly striving to overcome the boundaries of our world in order to reach new horizons that provide us countless inspirations and lights, in harmony with the answers to be given to contemporary man, in search of a deep sense of his own becoming throughout history. Creativeness and purity are signs that, in the novelty of artistic languages, distinguish the longing to which the Frate Sole Foundation intends to bear witness strongly with a view to urging those involved in the field of sacred architecture to become champions, taking up the cause of authenticity and light.<\/i><\/p>\n<p>The Day will begin at <b>12:00 am<\/b> in the <b>courtyard of Palazzo Broletto<\/b> with the opening of the documentary exhibition <b><i>2016 &#8211; International Award for Sacred Architecture &#8211; participating churches and project guidelines<\/i><\/b>, collecting all the 86 projects that have participated in the 6<sup>th<\/sup> edition of the Award, which have been set up thanks to a self-supporting structure located beneath the porch, and visible to the public until October 11<sup>th<\/sup>.<\/p>\n<p>For each project, the images of the exterior and interior spaces have been put on display within the exhibition, alongside the related technical drawings, which illustrate with scientific rigour the construction of the various architectures, so as to make them comprehensible not only to field experts, but also to the general public. To be found on display there will also be the maquette made by the winner, the Spaniard Rafael Moneo. It is a model of the <i>Church of Jesu<\/i> in San Sebasti\u00e1n, which will then be donated to the Frate Sole Foundation.<\/p>\n<p>The <b>official prize-giving ceremony<\/b>, anchored by the famous architectural historian Francesco Dal Co, will begin at <b>3:00 pm<\/b> in the <b>Room of Frescoes of the Collegio Borromeo<\/b> in Pavia, including an institutional part with speeches of the city authorities, followed by the prize award \u2013 in the presence of the Chilean architect Cristian Undurraga, the winner of the last edition of the Award with the \u201cCapilla del Retiro\u201d (\u201cRetreat Chapel\u201d) &#8211; during which each finalist will expound to the attending audience their respective projects.<\/p>\n<p>The event will start with the special mentions (for the<i> Chapel of St. John the Baptist<\/i>, built in the Johannisthal district in Berlin by the German architectural design firm Br\u00fcckner &amp; Br\u00fcckner and the <i>Chapel of Saint John Baptist<\/i>, designed by the Spanish architect Alejandro Beautell in Tenerife, Canary Islands), who will receive a plaque specially designed by the Frate Sole Foundation. The event will continue with the German architectural design firm Schulz und Schulz, who has won the third prize with the <i>New Church St. Trinitatis<\/i> in the city of Leipzig (Germany), which will receive a cash contribution amounting to 5,000 Euros. The architects Thu Huong Thi Vu and Tuan Dung Nguyen, runners-up with the <i>New Parish Church of Ka Don<\/i> in Don Duong, in the Province of Lam Dong, Vietnam, will be awarded a contribution amounting to 10,000 Euros. Rafael Moneo, who has come first with the <i>Church of Iesu<\/i> in San Sebasti\u00e1n, will receive a cash contribution amounting to 15,000 Euros and the now famous \u201cCieldoro\u201d (\u201cGolden Sky\u201d), a polished steel reproduction of a sculpture made by Father Costantino on the occasion of the 1<sup>st<\/sup> edition of the International Award for Sacred Architecture in 1996.<\/p>\n<p>In conjunction with the prize-giving ceremony, <b>a scientific catalogue<\/b> will also be published in relation to the projects of the 6<sup>th<\/sup> Edition of the International Award for Sacred Architecture. The catalogue will include the pictures, drawings, and technical reports of the three winning projects and two special mentions, in addition to the grounds of the Jury, the architects\u2019 biographies and a small part reserved for the other participants in the 2016 edition.<\/p>\n<p>The International Prize for Sacred Architecture is organized by the Frate Sole Foundation and sponsored by local authorities and national ecclesiastical and cultural institutes, such as the Pontifical Commission for the Ecclesiastic Cultural Heritage of the Holy See, the Ministry of Heritage and Culture, the National Council of Architects, the Order of Landscaping Architects of the Province of Pavia, the Diocese of Pavia, the Municipality of Pavia, the University of Pavia, the National Bureau for Sacred Buildings, and the Province S. Antonio of the Friars Minor.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4494\" src=\"http:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/09\/Alejandro-Beautell-2.jpg\" alt=\"alejandro-beautell-2\" width=\"1086\" height=\"768\" srcset=\"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/09\/Alejandro-Beautell-2.jpg 1086w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/09\/Alejandro-Beautell-2-300x212.jpg 300w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/09\/Alejandro-Beautell-2-768x543.jpg 768w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/09\/Alejandro-Beautell-2-1024x724.jpg 1024w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/09\/Alejandro-Beautell-2-600x424.jpg 600w\" sizes=\"auto, (max-width: 1086px) 100vw, 1086px\" \/><\/p>\n<pre>INFO\r\nPremio Internazionale di Architettura Sacra\r\nVI edizione - 2016 -\u00a0Pavia\r\nGiornata di premiazione - marted\u00ec 4 ottobre\r\nore 12 nel cortile di Palazzo Broletto\r\n\r\n<\/pre>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">\u23f0 lettura <\/span> <span class=\"rt-time\"> 7<\/span> <span class=\"rt-label rt-postfix\">min. <\/p>\n<p><\/span><\/span>Fondazione Frate Sole Giornata di premiazione &#8211; marted\u00ec 4 ottobre Premio Internazionale di Architettura Sacra VI edizione &#8211; 2016 &#8211;\u00a0Pavia In occasione della festivit\u00e0 di San Francesco d&#8217;Assisi, marted\u00ec 4 ottobre si svolger\u00e0 a Pavia la Giornata di premiazione per la VI edizione del Premio Internazionale di Architettura Sacra, un&#8217;occasione per riflettere sul dibattito contemporaneo&hellip;&nbsp;<a href=\"https:\/\/www.biancoscuro.it\/site\/premio-internazionale-architettura-sacra-pavia\/\" rel=\"bookmark\">Leggi tutto &raquo;<span class=\"screen-reader-text\">Premio Internazionale di Architettura Sacra &#8211; Pavia<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":4498,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"footnotes":""},"categories":[5,28,26,24],"tags":[],"class_list":["post-4493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte","category-concorso","category-eventi","category-mostre"],"jetpack_featured_media_url":"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/09\/Vietnam.jpg","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":14884,"url":"https:\/\/www.biancoscuro.it\/site\/arte-sacre-arte-spirituale-di-gianmaria-potenza\/","url_meta":{"origin":4493,"position":0},"title":"Arte Sacra Arte Spirituale di Gianmaria Potenza","author":"Elena Seno","date":"14 Novembre 2022","format":false,"excerpt":"Con la mostra Arte Sacra Arte Spirituale si vuole celebrare quella parte di produzione artistica dedicata alla spiritualit\u00e0 del maestro Gianmaria Potenza, che per l\u2019occasione ha creato dei nuovi arredi sacri per la Cattedrale di Cremona.Lo scultore e designer veneziano aveva gi\u00e0 lavorato in ambito religioso in passato, trovando un\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2022\/11\/Arte-Sacra-Arte-Spirituale-Mostra-Gian-Maria-Potenza-313073936_454401246834862_6911811864527614984_n.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2022\/11\/Arte-Sacra-Arte-Spirituale-Mostra-Gian-Maria-Potenza-313073936_454401246834862_6911811864527614984_n.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2022\/11\/Arte-Sacra-Arte-Spirituale-Mostra-Gian-Maria-Potenza-313073936_454401246834862_6911811864527614984_n.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":8200,"url":"https:\/\/www.biancoscuro.it\/site\/al-museo-del-paesaggio-di-verbania-in-mostra-i-progetti-della-10-biennale-del-paesaggio-di-barcellona\/","url_meta":{"origin":4493,"position":1},"title":"Al Museo del Paesaggio di Verbania in mostra i progetti della 10\u00b0 Biennale del Paesaggio di Barcellona","author":"Chiara","date":"7 Novembre 2018","format":false,"excerpt":"Dal 17 novembre 2018 al 6 gennaio 2019 il MUSEO DEL PAESAGGIO DI VERBANIA ospita una mostra multimediale che raccoglie tutti i progetti presentati in concorso alla 10a edizione della BIENNALE INTERNAZIONALE DEL PAESAGGIO DI BARCELLONA. La Biennale di Barcellona \u00e8 stata riconosciuta negli anni come un punto di riferimento\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/11\/27.-QUZHOU-LUMING-PARK.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/11\/27.-QUZHOU-LUMING-PARK.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/11\/27.-QUZHOU-LUMING-PARK.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/11\/27.-QUZHOU-LUMING-PARK.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":4051,"url":"https:\/\/www.biancoscuro.it\/site\/1-festa-dellarchitettura-dabruzzo-architetture_visioni-contemporanee\/","url_meta":{"origin":4493,"position":2},"title":"1\u00b0 Festa dell\u2019Architettura d\u2019Abruzzo: archiTEtture_visioni contemporanee","author":"Roberta Melasecca","date":"11 Giugno 2016","format":false,"excerpt":"1\u00b0 Festa dell\u2019Architettura d\u2019Abruzzo archiTEtture_visioni contemporanee 14\/24 giugno 2016 Inaugurazione 14 giugno 2016 ore 15.30 L\u2019Arca Laboratorio per le Arti Contemporanee | Largo S. Matteo | Teramo \u00a0 La Federazione degli Ordini degli Architetti PPC. Abruzzo Molise e l\u2019Ordine degli Architetti PPC. della Provincia di Teramo, in collaborazione con l\u2019Ordine\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/06\/1%C2%B0-festa-dellarchitettura-dabruzzo-WEB-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/06\/1%C2%B0-festa-dellarchitettura-dabruzzo-WEB-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/06\/1%C2%B0-festa-dellarchitettura-dabruzzo-WEB-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":2330,"url":"https:\/\/www.biancoscuro.it\/site\/torna-paviart-2015-terza-edizione-artistica-della-mostra-mercato-pavese\/","url_meta":{"origin":4493,"position":3},"title":"Torna PaviArt 2015, terza edizione artistica della mostra mercato pavese","author":"Redazione BIANCOSCURO","date":"3 Marzo 2015","format":false,"excerpt":"Dal 24 al\u00a026 aprile 2015 torna PaviArt, grande appuntamento per la citt\u00e0 di Pavia, citt\u00e0 d\u2019arte e di cultura. Gi\u00e0\u00a0capitale del\u00a0Regno\u00a0Longobardo,\u00a0Pavia \u00e8 sede di una delle pi\u00f9 antiche\u00a0universit\u00e0\u00a0italiane. Le origini antiche ed un passato di grande importanza hanno lasciato a Pavia un patrimonio artistico notevole. Tra le attrazioni\u00a0turistiche\u00a0principali possiamo ammirare:\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"biancoscuro PAVIART 2015","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2015\/03\/locandinaPAVIART2015.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3275,"url":"https:\/\/www.biancoscuro.it\/site\/premio-biennale-oscar-per-le-arti-visive-e-premiazione-biancoscuro-art-contest\/","url_meta":{"origin":4493,"position":4},"title":"Premio Biennale Oscar per le Arti Visive e premiazione BIANCOSCURO Art Contest","author":"Redazione BIANCOSCURO","date":"19 Ottobre 2015","format":false,"excerpt":"L'appuntamento Biennale dell\u2019Arte, giunto ormai alla ottava edizione, Oscar per le Arti Visive\u00a0si svolger\u00e0 \u00a0Sabato 24 Ottobre 2015 Monte-Carlo Bay, Principato di Monaco. Il Premio conferito da ArtExp\u00f2 Gallery, \u00e8 il giusto riconoscimento per la professionalit\u00e0, ricerca e creativit\u00e0. La prima edizione della cerimonia risale al febbraio 2001 ed al\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2015\/09\/Monte-Carlo2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2015\/09\/Monte-Carlo2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2015\/09\/Monte-Carlo2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2015\/09\/Monte-Carlo2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":10997,"url":"https:\/\/www.biancoscuro.it\/site\/la-materia-diventa-forma-costantino-ruggeri\/","url_meta":{"origin":4493,"position":5},"title":"La materia diventa forma | Costantino Ruggeri","author":"Redazione BIANCOSCURO","date":"31 Agosto 2020","format":false,"excerpt":"Visibile fino al 4 ottobre a Pavia, nello spazio arti contemporanee del Broletto, la mostra \u201cDalla materia alla forma\u201d, opere di Costantino Ruggeri realizzate negli anni '60 e '70. \u201cLa materia diventa forma\u201d, nel 1967, segna la nascita del movimento dell\u2019arte povera da parte del critico d'arte (recentemente scomparso) Germano\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2020\/09\/Costantino-Ruggeri_LOCANDINA.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2020\/09\/Costantino-Ruggeri_LOCANDINA.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2020\/09\/Costantino-Ruggeri_LOCANDINA.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/4493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/comments?post=4493"}],"version-history":[{"count":0,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/4493\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/media\/4498"}],"wp:attachment":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/media?parent=4493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/categories?post=4493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/tags?post=4493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}