{"id":6515,"date":"2018-02-14T09:44:31","date_gmt":"2018-02-14T08:44:31","guid":{"rendered":"https:\/\/www.biancoscuro.it\/site\/?p=6515"},"modified":"2018-02-15T10:55:15","modified_gmt":"2018-02-15T09:55:15","slug":"spilli-installazione-ambientale-nel-lago-ex-snia-alberto-timossi-sistema-sonoro-simone-pappalardo","status":"publish","type":"post","link":"https:\/\/www.biancoscuro.it\/site\/spilli-installazione-ambientale-nel-lago-ex-snia-alberto-timossi-sistema-sonoro-simone-pappalardo\/","title":{"rendered":"SPILLI. Installazione ambientale\/sonora"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">\u23f0 lettura <\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">min. <br><br><\/span><\/span><p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6517\" src=\"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/02\/spilli.jpg\" alt=\"\" width=\"2048\" height=\"1466\" srcset=\"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/02\/spilli.jpg 2048w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/02\/spilli-300x215.jpg 300w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/02\/spilli-768x550.jpg 768w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/02\/spilli-1024x733.jpg 1024w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/02\/spilli-600x429.jpg 600w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/02\/spilli-1320x945.jpg 1320w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><\/p>\n<h4><\/h4>\n<h3>Il giorno <i>17 febbraio 2018<\/i> <b>Alberto Timossi<\/b> e <b>Simone Pappalardo<\/b> presentano \u201c<b>Spilli<\/b>\u201d, installazione ambientale nel <i>Lago Ex Snia a Roma.\u00a0<\/i><\/h3>\n<p>Il Lago Ex Snia \u00e8 la conferma che la Natura prima o poi si riappropria sempre e comunque dello spazio che le \u00e8 stato tolto: nato nel 1993 in seguito agli effetti di una speculazione edilizia, mai riuscita, che aveva intercettato inavvertitamente una falda acquifera, ora il lago ha visto sviluppare un ecosistema straordinario, ricco di specie protette. L&#8217;area del lago \u00e8 in parte di propriet\u00e0 pubblica: il Forum del Parco delle Energie, che da due anni coordina l&#8217;apertura autogestita dell&#8217;area, sta lavorando per il suo riconoscimento come Monumento Naturale.<\/p>\n<p>Il tentativo di costruire su un suolo evidentemente inadatto ha permesso alla Natura di recuperare l\u2019area che le era stata tolta, e lo ha fatto con un grande effetto speciale: facendo nascere un lago. La mossa della Natura \u00e8 astuta, non c\u2019\u00e8 possibilit\u00e0 di ritorno, la bilancia pesa dalla sua parte: cos\u00ec facendo, ha permesso al suo regno di attecchire, ricordandoci che \u00e8 nelle sue possibilit\u00e0 continuare a stupirci.<\/p>\n<p>In questo contesto, ad esaltare la sua potenziale magia, apparir\u00e0, all\u2019improvviso, un canneto rosso, come una nuova piantagione. Si tratta tuttavia di un avvertimento: i margini sono quasi raggiunti; oltre, la Natura non osserver\u00e0 pi\u00f9 le regole. L\u2019Antropocene \u00e8 anche questo, il pericolo che il controllo ci sfugga di mano e il \u201cprogresso\u201d prenda pieghe inaspettate e non calcolabili a priori.<\/p>\n<p>Il canneto \u00e8 sottile e folto; sulle punte sono inserite delle capocchie di spillo, sfere che come teste si rivolgono verso l\u2019alto. Le canne ondulano al vento e cantano melodie appena percettibili, alimentando il corpus sonoro gi\u00e0 presente nell\u2019<i>oasi<\/i> urbana.<\/p>\n<p>Gli spilli assumono anche la funzione di <i>indicatori<\/i> che segnalano ed indicano una realt\u00e0 in mutazione proprio nell\u2019acqua del nuovo lago: nell\u2019acqua che \u00e8 sinonimo di vita, di cultura e di civilt\u00e0, nell\u2019acqua che comincer\u00e0 a scarseggiare se il clima non fermer\u00e0 la sua corsa eversiva.<\/p>\n<p>Gli spilli, costituiti da materiali tratti dall\u2019edilizia non pregiati e non inquinanti, verranno installati, con l\u2019uso di gommone a remi e zattere, in un\u2019unica zona del lago, visibile sia dal prospetto principale, dall\u2019entrata del parco di Via di Portonaccio, sia dal passaggio laterale dove sono presenti le zattere. L\u2019opera quindi si colloca in una zona lontana dalla riva, di fronte all\u2019edificio non finito in cemento armato, senza interferire con i percorsi migratori degli uccelli.<\/p>\n<p>Il <b>24 febbraio <\/b>nello spazio <i>dMak<\/i>e e il <b>3 marzo<\/b> a <i>Curva Pura<\/i>, <b>Simone Pappalardo<\/b> e <b>Salvatore Insana<\/b> presenteranno \u201c<b><i>Lezioni timbriche di naufragio &#8211; <\/i><\/b><b><i>1. In un inghiotto galleggiare sul sopra del sotto<\/i><\/b><i>\u201d<\/i>, live electronics audio-video sul materiale estratto dall\u2019installazione <b><i>Spilli<\/i><\/b>,<b><i> <\/i><\/b>paradigma iniziale per il primo di una serie di interventi artistici sul tema dell\u2019affondamento e del naufragio.<\/p>\n<p>Il naufragio \u00e8, infatti, anche una condizione esistenziale, un processo in atto che opera sotterraneo nella stasi del nostro disagio quotidiano. I resti di strutture in cemento mai terminate, affioranti dalle acque limacciose del lago Ex Snia, i macchinari da lavoro sepolti dal limo, i mezzi tecnici erosi dall\u2019azione delle melme e deformati dalle alghe sono dunque fotografie di un percorso di disfatta e di rinascita.<\/p>\n<p>La prima lezione timbrica avr\u00e0 la forma di un live electronics per macchine sonore di Simone Pappalardo e video di Salvatore Insana. I materiali audio e video nascono, in parte, da azioni parassite di appropriazione momentanea dell\u2019opera di Alberto Timossi. Attraverso l\u2019uso di tecnologie povere, microfoni-idrofoni autocostruiti installati nell\u2019opera, obbiettivi artigianali e portatori di difetti, viene proposta un&#8217;operazione di assalto, di sabotaggio estetico.<\/p>\n<p>Come far affondare la visione? Il naufragio dei sensi \u00e8 questione delicata.<\/p>\n<p>Dare segnali che la resa estetica \u00e8 un&#8217;arma a doppio taglio, tra resistenza alla rincorsa tecnologica e rinuncia alla spettacolarizzazione, tra attenzione al dettaglio, al laterale, allo scarto e disarmo dell&#8217;alta definizione, in ascolto della natura, del respiro degli esseri, ad altezza uomo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6519\" src=\"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/02\/veduta-dinsieme-7-spilli.jpg\" alt=\"\" width=\"2048\" height=\"1536\" srcset=\"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/02\/veduta-dinsieme-7-spilli.jpg 2048w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/02\/veduta-dinsieme-7-spilli-300x225.jpg 300w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/02\/veduta-dinsieme-7-spilli-768x576.jpg 768w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/02\/veduta-dinsieme-7-spilli-1024x768.jpg 1024w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/02\/veduta-dinsieme-7-spilli-600x450.jpg 600w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/02\/veduta-dinsieme-7-spilli-1320x990.jpg 1320w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><\/p>\n<p style=\"text-align: center;\"><em>Work in progress<\/em><\/p>\n<pre><b>INFO<\/b>\r\n\r\n<b>SPILLI\r\n Installazione ambientale nel Lago ex Snia\r\n di Alberto Timossi\r\n Con sistema sonoro di Simone Pappalardo\u00a0<\/b>\r\n\r\nCon il contributo del <b>Forum del Parco delle Energie<\/b>\r\n\r\n<b>Inaugurazione installazione\r\n <\/b>17 febbraio 2018 ore 11.00\r\n Lago ex Snia - Via di Portonaccio - Roma\r\n\r\n<b>Lezioni timbriche di naufragio\r\n 1. In un inghiotto galleggiare sul sopra del sotto\r\n Live electronics audio-video di Simone Pappalardo e Salvatore Insana<\/b>\r\n 24 febbraio 2018 ore 18.00\r\n <b>dMake - <\/b><a href=\"https:\/\/maps.google.com\/?q=Via+G.+Lanza+174+-+Roma&amp;entry=gmail&amp;source=g\">Via G. Lanza 174 - Roma<\/a>\r\n\r\n<b>Lezioni timbriche di naufragio\r\n 1. In un inghiotto galleggiare sul sopra del sotto\r\n Live electronics audio-video di Simone Pappalardo e Salvatore Insana<\/b>\r\n 3 marzo 2018 ore 18.00\r\n <b>Curva Pura - <\/b><a href=\"https:\/\/maps.google.com\/?q=Via+Giuseppe+Acerbi+1+-+Roma&amp;entry=gmail&amp;source=g\">Via Giuseppe Acerbi 1 - Roma<\/a><\/pre>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">\u23f0 lettura <\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">min. <\/p>\n<p><\/span><\/span>Il giorno 17 febbraio 2018 Alberto Timossi e Simone Pappalardo presentano \u201cSpilli\u201d, installazione ambientale nel Lago Ex Snia a Roma.\u00a0 Il Lago Ex Snia \u00e8 la conferma che la Natura prima o poi si riappropria sempre e comunque dello spazio che le \u00e8 stato tolto: nato nel 1993 in seguito agli effetti di una speculazione&hellip;&nbsp;<a href=\"https:\/\/www.biancoscuro.it\/site\/spilli-installazione-ambientale-nel-lago-ex-snia-alberto-timossi-sistema-sonoro-simone-pappalardo\/\" rel=\"bookmark\">Leggi tutto &raquo;<span class=\"screen-reader-text\">SPILLI. Installazione ambientale\/sonora<\/span><\/a><\/p>\n","protected":false},"author":980,"featured_media":6517,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"footnotes":""},"categories":[5,26,334,27,676,7],"tags":[],"class_list":["post-6515","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte","category-eventi","category-installazioni","category-manifestazione","category-performance","category-scultura"],"jetpack_featured_media_url":"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/02\/spilli.jpg","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":7615,"url":"https:\/\/www.biancoscuro.it\/site\/alberto-timossi-in-memoria-pietre-nere-per-il-lago-sofia\/","url_meta":{"origin":6515,"position":0},"title":"Alberto Timossi. In memoria &#8211; Pietre nere per il Lago Sofia","author":"Roberta Melasecca","date":"19 Luglio 2018","format":false,"excerpt":"Alberto Timossi presenta il progetto In memoria. Pietre nere per il Lago Sofia, esposizione condivisa di arte ambientale alla quota di 2670metri \u00a0del Ghiacciaio del Calderone sul Gran Sasso d\u2019Italia. Appuntamento per\u00a0il\u00a022 luglio 2018 al\u00a0Ghiacciaio del Calderone, Gran Sasso d\u2019Italia (2670 m) con partenza ore 7.30 dal Rifugio Franchetti. Il\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/07\/schizzo-1189-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/07\/schizzo-1189-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/07\/schizzo-1189-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/07\/schizzo-1189-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/07\/schizzo-1189-1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/07\/schizzo-1189-1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":7077,"url":"https:\/\/www.biancoscuro.it\/site\/dissonanze-monica-pennazzi-alberto-timossi\/","url_meta":{"origin":6515,"position":1},"title":"Dissonanze | Monica Pennazzi &#8211; Alberto Timossi","author":"Roberta Melasecca","date":"12 Aprile 2018","format":false,"excerpt":"Nel contesto della manifestazione AnconaCrea, giunta alla sua IV edizione, il 20 aprile 2018 alle ore 18.30 verr\u00e0 aperto Map 120\u00a0Magazzini Artistici Pennazzi\u00a0per lo studio visit dal titolo \u201cDissonanze\u201d. Map 120 \u00e8 un luogo del fare, uno studio che diventa spazio per l\u2019incontro e lo scambio tra gli artisti: 170\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/04\/locandina-map120-2018.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/04\/locandina-map120-2018.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/04\/locandina-map120-2018.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/04\/locandina-map120-2018.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":7253,"url":"https:\/\/www.biancoscuro.it\/site\/fata-morgana-la-fonte-sospesa-installazione-scultorea-di-alberto-timossi\/","url_meta":{"origin":6515,"position":2},"title":"Fata Morgana\/La fonte sospesa. Installazione scultorea di Alberto Timossi","author":"Roberta Melasecca","date":"16 Maggio 2018","format":false,"excerpt":"Fata Morgana\/La fonte sospesa Installazione scultorea di Alberto Timossi A cura di Marcello Barbanera\u00a0 18 maggio 2018 ore 11 |\u00a0 Fontana della Minerva - Sapienza Universit\u00e0 di Roma Fino al 16 giugno 2018 Il giorno 18 maggio 2018 alle ore 11.00 presso la Fontana della Minerva della Sapienza Universit\u00e0 di\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/05\/Fata-MorganaLa-fonte-sospesa-.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/05\/Fata-MorganaLa-fonte-sospesa-.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/05\/Fata-MorganaLa-fonte-sospesa-.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/05\/Fata-MorganaLa-fonte-sospesa-.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/05\/Fata-MorganaLa-fonte-sospesa-.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/05\/Fata-MorganaLa-fonte-sospesa-.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":18648,"url":"https:\/\/www.biancoscuro.it\/site\/grancaro-welcome-on-board-2025\/","url_meta":{"origin":6515,"position":3},"title":"GRANCARO welcome on board &#8211; 2025","author":"Roberta Melasecca","date":"1 Luglio 2025","format":false,"excerpt":"Grancaro welcome on board \u00e8 un progetto di Lorenzo e Francesco Cozza Caposavi, realizzato con la direzione artistica di Francesca Perti e Mara Van Wees, in collaborazione con Asp Tra le Volte di Francesco Pezzini. Inaugurazione 12 luglio 2025 ore 17.00. Presentazione catalogo ore 18.00.\u00a0 Il progetto Grancaro ha come\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/07\/GRANCARO-2025-copia.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/07\/GRANCARO-2025-copia.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/07\/GRANCARO-2025-copia.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/07\/GRANCARO-2025-copia.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":6920,"url":"https:\/\/www.biancoscuro.it\/site\/armonie-verdi-paesaggi-dalla-scapigliatura-al-novecento\/","url_meta":{"origin":6515,"position":4},"title":"ARMONIE VERDI | Paesaggi dalla Scapigliatura al Novecento","author":"Chiara","date":"21 Marzo 2018","format":false,"excerpt":"Il Museo del Paesaggio di Verbania - dopo la riapertura nel 2016 con la splendida mostra dedicata a Paolo Troubetzkoy aperta in modo permanente al piano terra e la bella rassegna del 2017 I volti e il cuore, sulla figura femminile tra Otto e Novecento - riapre la stagione primaverile\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/03\/9.-Gnecchi-Fondo-Toce-Lago-Maggiore-1884.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/03\/9.-Gnecchi-Fondo-Toce-Lago-Maggiore-1884.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/03\/9.-Gnecchi-Fondo-Toce-Lago-Maggiore-1884.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/03\/9.-Gnecchi-Fondo-Toce-Lago-Maggiore-1884.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/03\/9.-Gnecchi-Fondo-Toce-Lago-Maggiore-1884.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/03\/9.-Gnecchi-Fondo-Toce-Lago-Maggiore-1884.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":7220,"url":"https:\/\/www.biancoscuro.it\/site\/il-gioco-e-larte-per-tornare-a-vivere-installazioni-artistiche-nel-nuovo-parco-giochi-di-amatrice\/","url_meta":{"origin":6515,"position":5},"title":"Il gioco (e l\u2019arte) per tornare a vivere.\u00a0Installazioni artistiche nel nuovo Parco Giochi di Amatrice","author":"Roberta Melasecca","date":"9 Maggio 2018","format":false,"excerpt":"Il gioco (e l\u2019arte) per tornare a vivere. Installazioni artistiche nel nuovo Parco Giochi di Amatrice Roberta Morzetti - Angelo Savarese - Alberto Timossi - Stefano Trappolini A cura di Velia Littera della Galleria Pavart di Roma Con il patrocinio del Comune di Amatrice Inaugurazione 12 maggio 2018 ore 12.00\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/05\/Parco-amatrice.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/05\/Parco-amatrice.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/05\/Parco-amatrice.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/6515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/users\/980"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/comments?post=6515"}],"version-history":[{"count":0,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/6515\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/media\/6517"}],"wp:attachment":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/media?parent=6515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/categories?post=6515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/tags?post=6515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}