{"id":7232,"date":"2018-05-15T08:51:11","date_gmt":"2018-05-15T06:51:11","guid":{"rendered":"https:\/\/www.biancoscuro.it\/site\/?p=7232"},"modified":"2018-05-15T08:51:11","modified_gmt":"2018-05-15T06:51:11","slug":"at-home-lucca-art-fair","status":"publish","type":"post","link":"https:\/\/www.biancoscuro.it\/site\/at-home-lucca-art-fair\/","title":{"rendered":"AT HOME &#8211; Lucca Art Fair"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">\u23f0 lettura <\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">min. <br><br><\/span><\/span><p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7233\" src=\"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/05\/AT-HOME.jpg\" alt=\"\" width=\"1500\" height=\"597\" srcset=\"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/05\/AT-HOME.jpg 1500w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/05\/AT-HOME-300x119.jpg 300w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/05\/AT-HOME-768x306.jpg 768w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/05\/AT-HOME-1024x408.jpg 1024w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/05\/AT-HOME-600x239.jpg 600w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/05\/AT-HOME-1320x525.jpg 1320w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><\/p>\n<p><b>AT HOME<br \/>\n<\/b>A cura di Carmelo Cipriani<br \/>\n<b>Lucca Art Fair<br \/>\n18 &#8211; 20 maggio 2018<\/b><\/p>\n<p>La <b>C23HomeGallery<\/b> sar\u00e0 presente alla <b>terza <\/b><b>edizione <\/b>di<b> Lucca <\/b><b>Art Fair, <\/b>dal 18 al 20 maggio 2018, dove presenta il progetto <b>AT HOME<\/b>, a cura di <b>Carmelo Cipriani,<\/b> interpretato da<b> Pamela Napoletano, Federica Limongelli, Evita Andujar, Toni Alfano, Maria d\u2019Anna, Giuseppe Monzo, Costabile Guariglia, Gianni Grattacaso.<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/p>\n<p>Il catalogo, pubblicato da <i>NCF edizioni<\/i>, a cura di <i>Carmelo Cipriani<\/i>, sar\u00e0 presentato nello spazio <b>Talk <\/b><i>sabato 18 maggio alle ore 12.00.<\/i><\/p>\n<p>\u201cCondizione esistenziale oltre che materiale, la casa \u00e8 il luogo della convivenza, la spazio in cui ciascuno \u00e8 libero di mostrarsi, agevolato in questo da un&#8217;atmosfera informale e da un contesto familiare. Il \u201csentirsi a casa\u201d \u00e8 una necessit\u00e0, un bisogno imprescindibile per stare bene con se stessi e con gli altri. Non esiste individuo che non cerchi il suo posto nel mondo, che non brami di vivere \u201ca casa\u201d, a prescindere da dove sia nato o cresciuto. Pu\u00f2 anche trattarsi di un luogo sconosciuto ma che per opportunit\u00e0, accoglienza, bellezza e altre svariate ragioni, non sempre spiegabili, pu\u00f2 farci sentire a casa.<\/p>\n<p>Determinato da una vera e propria affinit\u00e0 elettiva, il concetto di casa \u00e8 mutevole, geograficamente estendibile, dalla sola abitazione ad un intero Stato, salvo poi annullare ogni consistenza materiale in favore di una dimensione interiore, determinata dalle persone prima che dalle mura. La mostra \u201cAt Home\u201d attinge alla dimensione immateriale, basandosi sulla\u00a0duplice declinazione del concetto di casa, al tempo stesso luogo di appartenenza e d\u2019incontro. Promossa da C23 Home Gallery di Lucca, essa stessa concept prima che luogo fisico, la mostra affianca la soluzioni formali di otto artisti profondamente diversi tra loro, allo scopo di mostrarne le precipue qualit\u00e0, nell&#8217;ottica della reciproca valorizzazione. Un incontro largo, continuamente rimodulabile, privo di costrizioni tematiche o restringimenti iconografici, fondato sullo stare insieme, qui ed ora.\u201d (<i>dal testo critico di Carmelo Cipriani<\/i>)<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Un progetto proposto all\u2019interno dello stand per una mostra site specific, volto a esaltare l\u2019arte contemporanea come strumento fuori linea: di confronto e di approfondimento, conoscenza dell\u2019altro e superamento delle differenze. La ricerca degli artisti presentati per l\u2019evento di Lucca ArtFair indaga diversi linguaggi spaziando dalla pittura al digitale, dalla videoinstallazione e mixed media. Le opere esprimono una sintesi della diversa significazione nella singolare estetica contemporanea elaborata secondo la personale esigenza di percorso.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>L\u2019approccio di AT HOME avvalora e amplifica gli apporti sensibili che si accompagnano abitualmente alle opere di questi artisti emergenti con l\u2019interpretazione delle dinamiche di un ambiente fieristico che si svolge in un\u2018area e in volume recuperati alla comunicazione del linguaggio dell\u2019arte che spazia dal figurativo al concettuale, da artisti storicizzati a giovani artisti.<\/p>\n<p>Si inizia con <b>Pamela Napoletano<\/b> che adotta il\u00a0 vuoto come condizione gnoseologica, dimensione da indagare mediante una pittura multimaterica, con inserti eterogenei, pittorici, a collage o assemblati. Sospesa tra il familiare e il perturbante, la sua recente ricerca attinge alla natura ambivalente del vuoto, travolgente e rasserenante, assenza e possibilit\u00e0 generativa.<\/p>\n<p><b>Federica Limongelli<\/b>, che al simbiotico rapporto tra tela e pennello ha preferito l\u2019immaterialit\u00e0 della digital painting, riconoscendo nello schermo e nei pixel la nuova frontiera della pittura.<\/p>\n<p><b>Evita Andujar,<\/b> da sempre interessata alla dimensione liminale tra indagine del reale e la sua restituzione metafisica. <b>Toni Alfano,<\/b> che sulla tela inscena un\u2019indagine particellare sulla memoria e sull\u2019identit\u00e0 personale.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p><b>Maria D\u2019Anna<\/b>, che guarda all\u2019arte come spazio aperto alla sperimentazione, spaziando dalla pittura all\u2019installazione, al video.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>All\u2019eterogeneit\u00e0 materica ed esecutiva guarda anche <b>Giuseppe Monzo<\/b> che pensa e agisce nell\u2019arte prima come pensatore che come esecutore, considerando l\u2019attivit\u00e0 progettuale propedeutica alla produzione materiale, libera ma sempre premeditata. <b>Costabile Guariglia<\/b> che utilizza indifferentemente pittura, video e performance, subordinando la visione alla creazione pura, non di rado sconnessa dal dato fenomenico.<\/p>\n<p>Chiude il gruppo <b>Gianni Grattacaso<\/b>, fotografo con una spiccata propensione per il disegno. Due passioni coniugate nel recente lavoro Animami, un viaggio nella memoria di una figura che vaga tra le stanze di un castello abbandonato da tempo.<\/p>\n<p>Il concept costruito da <i>C23HomeGallery <\/i>viene individuato all\u2019interno di una geografia di luoghi e spazi istituzionali dove presenta mostre d\u2019arte contemporanea agendo in modo itinerante, promuovendo artisti emergenti che producono opere in linea con l\u2019idea di valorizzazione di un\u2019arte da inserire nei circuiti del giovane collezionismo e non solo, selezionati attraverso i criteri del sistema di mercato dell\u2019arte contemporanea e adeguati alle esigenze della trasformazione in corso del commercio dell\u2019opera d&#8217;arte anche in seguito alle molteplici occasioni offerte dalle fiere che si tengono ogni anno di cui C23HomeGallery \u00e8 attiva e partecipe.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p><b>INFO<\/b><\/p>\n<p><b>AT HOME<br \/>\n<\/b>A cura di Carmelo Cipriani<br \/>\n<b>18 &#8211; 20 maggio 2018<br \/>\n<\/b>Stand G2<\/p>\n<p><b>Lucca Art Fair<br \/>\n<\/b>Polo Fiere Lucca &#8211; Via della Chiesa XXXII &#8211; trav. I, 237 &#8211; Lucca<br \/>\nwww.luccaartfair.it<\/p>\n<p><b>Orari:<\/b> venerd\u00ec 15-20 \/ sabato 11-20 \/ domenica 11-20<\/p>\n<p><b>Presentazione catalogo a cura di Carmelo Cipriani<br \/>\n<\/b>NCF edizioni<br \/>\n<b>18 maggio ore 12.00<br \/>\n<\/b>Spazio Talk Lucca Art Fair &#8211; Lucca<\/p>\n<p><b>C23HomeGallery<br \/>\nArt Director Raimondo Pinna<br \/>\n<\/b>+ 39 \/ 0583493191<br \/>\nC23homegallery@gmail.com<br \/>\n<a href=\"http:\/\/www.c23homegallery.wordpress.com\/\">www.c23homegallery.wordpress.com<\/a><\/p>\n<p><b>Ufficio Stampa<br \/>\nMelasecca PressOffice <\/b>Roberta Melasecca<br \/>\n3494945612<br \/>\n<a href=\"mailto:roberta.melasecca@gmail.com\">roberta.melasecca@gmail.com<\/a><br \/>\n<a href=\"http:\/\/www.melaseccapressoffice.it\">www.melaseccapressoffice.it<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">\u23f0 lettura <\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">min. <\/p>\n<p><\/span><\/span>AT HOME A cura di Carmelo Cipriani Lucca Art Fair 18 &#8211; 20 maggio 2018 La C23HomeGallery sar\u00e0 presente alla terza edizione di Lucca Art Fair, dal 18 al 20 maggio 2018, dove presenta il progetto AT HOME, a cura di Carmelo Cipriani, interpretato da Pamela Napoletano, Federica Limongelli, Evita Andujar, Toni Alfano, Maria d\u2019Anna,&hellip;&nbsp;<a href=\"https:\/\/www.biancoscuro.it\/site\/at-home-lucca-art-fair\/\" rel=\"bookmark\">Leggi tutto &raquo;<span class=\"screen-reader-text\">AT HOME &#8211; Lucca Art Fair<\/span><\/a><\/p>\n","protected":false},"author":980,"featured_media":7233,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"footnotes":""},"categories":[5,26,25,27,24],"tags":[],"class_list":["post-7232","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte","category-eventi","category-fiere","category-manifestazione","category-mostre"],"jetpack_featured_media_url":"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/05\/AT-HOME.jpg","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":6725,"url":"https:\/\/www.biancoscuro.it\/site\/vernice-art-fair-2018-gli-eventi-collaterali-le-gallerie-le-associazioni-e-gli-artisti-presenti\/","url_meta":{"origin":7232,"position":0},"title":"Vernice Art Fair 2018, gli eventi collaterali, le gallerie, le associazioni e gli artisti presenti","author":"Redazione BIANCOSCURO","date":"12 Marzo 2018","format":false,"excerpt":"Vernice Art Fair 2018 . 16\u00aa edizione \u00a0A Forl\u00ec dal 16 al 18 marzo 2018,\u00a0apertura venerd\u00ec 16 alle ore 16.30, i giorni successivi dalle\u00a010.00 alle 19.30. Ingresso omaggio per i lettori BIANCOSCURO Clicca qui per scaricare il biglietto omaggio! Gli eventi collaterali, le gallerie, le associazioni e gli artisti presenti\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/03\/BIANCOSCUROvernice2018.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/03\/BIANCOSCUROvernice2018.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/03\/BIANCOSCUROvernice2018.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":7818,"url":"https:\/\/www.biancoscuro.it\/site\/contemporary-art-fair-zurich\/","url_meta":{"origin":7232,"position":1},"title":"Contemporary Art Fair Zurich","author":"Redazione BIANCOSCURO","date":"19 Settembre 2018","format":false,"excerpt":"La 20\u00aa edizione al PULS 5 Il Contemporary Art Fair Zurich, importante e affermato appuntamento per l\u2019Arte a Zurigo, conferma anche per il 2018 la nuova location: la 21\u00aa edizione della kermesse si terr\u00e0 al PULS5 in Giessereistrasse 18.L\u2019inaugurazione \u00e8 fissata per il 20 settembre alle ore 18; le opere\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"ArtZurich 2018","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/09\/2000artzurich_17_11_29_Pro.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/09\/2000artzurich_17_11_29_Pro.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/09\/2000artzurich_17_11_29_Pro.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/09\/2000artzurich_17_11_29_Pro.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/09\/2000artzurich_17_11_29_Pro.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/09\/2000artzurich_17_11_29_Pro.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":3587,"url":"https:\/\/www.biancoscuro.it\/site\/art-parma-fair-4a-edizione-primavera-2016\/","url_meta":{"origin":7232,"position":2},"title":"Art Parma Fair, 4\u00aa edizione &#8211; primavera 2016","author":"Redazione BIANCOSCURO","date":"25 Febbraio 2016","format":false,"excerpt":"Due fine settimana dedicati all\u2019Arte a Fiere di Parma Ritorna\u00a0ART PARMA FAIR, fiera dedicata all\u2019arte moderna e contemporanea, nelle date\u00a027-28 febbraio\u00a0e\u00a04-5-6 marzo 2016\u00a0presso il quartiere fieristico parmense, in concomitanza con\u00a0Mercanteinfiera\u00a0e\u00a0Mercanteinauto. Gli ottimi\u00a0risultati delle vendite dell\u2019edizioni precedenti hanno riconosciuto l\u2019importanza di una piazza come Parma, che a buon titolo potr\u00e0 collocarsi\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/02\/aaa.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/02\/aaa.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/02\/aaa.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/02\/aaa.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/02\/aaa.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/02\/aaa.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":3210,"url":"https:\/\/www.biancoscuro.it\/site\/art-parma-fair-edizione-autunnale\/","url_meta":{"origin":7232,"position":3},"title":"Art Parma Fair, edizione autunnale","author":"Redazione BIANCOSCURO","date":"30 Settembre 2015","format":false,"excerpt":"Due fine settimana dedicati all\u2019Arte a Fiere di Parma Parma torna ad essere il centro dell\u2019arte con Art Parma Fair, mostra-mercato dedicata all\u2019arte moderna e contemporanea, presso il quartiere fieristico parmense, in concomitanza con Mercanteinfiera e Mercanteinauto. L\u2019ottimo risultato delle vendite dell\u2019edizione primaverile ha riconosciuto l\u2019importanza di una piazza come\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2015\/09\/COP.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2015\/09\/COP.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2015\/09\/COP.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":7388,"url":"https:\/\/www.biancoscuro.it\/site\/rhy-art-fair-basel-2018\/","url_meta":{"origin":7232,"position":4},"title":"Rhy ART Fair Basel 2018","author":"Redazione BIANCOSCURO","date":"8 Giugno 2018","format":false,"excerpt":"La quarta edizione tradizionalmente\u00a0sulle sponde del Reno Dal 14 al 17 giugno, nel Rhypark Hall Basel verranno presentate opere di 40 artisti indipendenti: dipinti, sculture, fotografia d\u2019arte, arte digitale e molto altro ancora. L\u2019obiettivo di Rhy Art Fair, \u00e8 anche per il 2018, il complemento delle fiere e degli eventi\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/06\/aaa.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/06\/aaa.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/06\/aaa.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/06\/aaa.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":8811,"url":"https:\/\/www.biancoscuro.it\/site\/vernice-art-fair-2019\/","url_meta":{"origin":7232,"position":5},"title":"Vernice Art Fair 2019","author":"Redazione BIANCOSCURO","date":"21 Febbraio 2019","format":false,"excerpt":"La 17\u00aa edizione della fiera dedicata agli artisti La 17\u00aa edizione di Vernice Art Fair, sar\u00e0 aperta al pubblico dal 15 al 17 marzo, come di consueto presso la Fiera di Forl\u00ec. Molte le importanti conferme: torner\u00e0 infatti a pregiarsi della presenza di un grande artista che ormai da anni\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2019\/02\/52586312_536527016756160_7310173073825595392_o.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2019\/02\/52586312_536527016756160_7310173073825595392_o.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2019\/02\/52586312_536527016756160_7310173073825595392_o.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2019\/02\/52586312_536527016756160_7310173073825595392_o.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2019\/02\/52586312_536527016756160_7310173073825595392_o.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/7232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/users\/980"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/comments?post=7232"}],"version-history":[{"count":0,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/7232\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/media\/7233"}],"wp:attachment":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/media?parent=7232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/categories?post=7232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/tags?post=7232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}