{"id":7861,"date":"2018-09-25T12:26:12","date_gmt":"2018-09-25T10:26:12","guid":{"rendered":"https:\/\/www.biancoscuro.it\/site\/?p=7861"},"modified":"2018-09-26T08:59:37","modified_gmt":"2018-09-26T06:59:37","slug":"mater-dolorosa-performance-art-di-e-con-mandra-cerrone","status":"publish","type":"post","link":"https:\/\/www.biancoscuro.it\/site\/mater-dolorosa-performance-art-di-e-con-mandra-cerrone\/","title":{"rendered":"Mater Dolorosa | Performance Art &#8211; Mandra Cerrone"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">\u23f0 lettura <\/span> <span class=\"rt-time\"> 2<\/span> <span class=\"rt-label rt-postfix\">min. <br><br><\/span><\/span>\n<p><br \/><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7863\" src=\"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/09\/Mater-Dolorosa-Mandra-Cerrone.jpg\" alt=\"\" width=\"1500\" height=\"1282\" srcset=\"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/09\/Mater-Dolorosa-Mandra-Cerrone.jpg 1500w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/09\/Mater-Dolorosa-Mandra-Cerrone-300x256.jpg 300w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/09\/Mater-Dolorosa-Mandra-Cerrone-768x656.jpg 768w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/09\/Mater-Dolorosa-Mandra-Cerrone-1024x875.jpg 1024w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/09\/Mater-Dolorosa-Mandra-Cerrone-600x513.jpg 600w, https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/09\/Mater-Dolorosa-Mandra-Cerrone-1320x1128.jpg 1320w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><\/p>\n\n\n\n<p>Il\u00a0<strong>2 ottobre 2018 alle ore 18.00<\/strong>, presso l\u2019<em>Aurum &#8211; Sala D\u2019Annunzio<\/em> di Pescara, l\u2019<em>Assessorato alla Cultura Citt\u00e0 di Pescara<\/em> con l\u2019<em>Associazione Mystic Driver Art Lab<\/em> presenta <strong>Mater Dolorosa<\/strong>, performance art di e con <strong>Mandra Cerrone<\/strong>, a cura di <strong>Michela Becchis<\/strong>. Interverr\u00e0 <strong>Giovanni Di Iacovo<\/strong>, Assessore alla Cultura del Comune di Pescara.<\/p>\n\n\n\n<p>\u201cNulla come una performance mette in gioco il corpo dell\u2019artista. Pu\u00f2 sembrare una banalit\u00e0 e tuttavia conviene considerare quanto corpo di artista ci sia sempre in un\u2019opera d\u2019arte, ma come, solo nella performance, l\u2019artista concede che si acceda al suo corpo.\u00a0<\/p>\n\n\n\n<p>\u00c8 molto tempo che si \u00e8 aggredita la nozione di collettivit\u00e0 e con questa l\u2019idea stessa di con-doglianza. In un\u2019epoca venduta come l\u2019apice massimo della socialit\u00e0 o della media socialit\u00e0, in realt\u00e0 si \u00e8 lavorato moltissimo a quella che Marx chiamava la <em>produzione dell\u2019individuo isolato<\/em>. Fuori dalla comunit\u00e0, fuori dalla pericolosa dialettica delle aspettative, dei bisogni, dei desideri, della partecipazione. E anche della compassione. Si \u00e8 riuscito a far credere che l\u2019individuo isolato\u00a0 sia l\u2019individuo finalmente libero e capace di autoprodursi e autorappresentarsi, mentre si creavano e si creano creature sole e perci\u00f2 inoffensive. O almeno si crede. Tralasciando una riflessione di sola politica (parola che oggi spaventa, ma che individua uno stare in comune ancora di grande valore) che non compete a queste righe, a svelare l\u2019inganno molto hanno contribuito il pensiero di genere e quello artistico. Un\u2019idea molto bella che li accomuna \u00e8 quello di vulnerabilit\u00e0. (&#8230;)<\/p>\n\n\n\n<p>Nella sua ricerca di un punto di vista da cui guardare il mondo, immergendosene fino ad ascoltare il battito del suo cuore, Mandra Stella Cerrone, nelle sue <em>performance<\/em>, \u00e8 sempre partita fattualmente da s\u00e9, cio\u00e8 mettendo in gioco frammenti del suo esistere. In <em>Mater Dolorosa<\/em> compie un altro, difficile, passo: partire da s\u00e9 eliminando il biografema per fare in modo che il suo s\u00e9 racconti le altre. Nella storia delle donne \u00e8 sempre esistita, spesso seguendo una tradizione orale, l\u2019autobiografia collettiva, cio\u00e8 un narrare la storia come se fosse la propria vicenda personale o piuttosto come se la propria vicenda personale si disponesse dentro la coralit\u00e0 frutto del tessuto di relazioni femminili. (&#8230;) Se nella tradizione cristiana il corporale \u00e8 il panno dove viene poggiata l\u2019ostia, cio\u00e8 un simulacro di corpo, Mandra Stella Cerrone trasforma in corporale laico, quel che resta di quella parte di s\u00e9 smembrata via. L\u2019abito, che le madri piegano come cura e estrema carezza al figlio perduto, si trasforma in <em>habitus<\/em>, cio\u00e8 il contenitore non solo del corpo negato ma anche delle attitudini, dei desideri, del carattere, dei sorrisi, della rabbia e della tenerezza di colui (eh gi\u00e0, quasi sempre un maschio) che mai pi\u00f9 indosser\u00e0 la vita.\u201d (<em>dal testo critico di Michela Becchis<\/em>)<\/p>\n\n\n\n<p><em><strong>Mandra Cerrone<\/strong>. Visual artist, performer, mystic driver. L\u2019arte \u00e8 la possibilit\u00e0 di condividere potenti strumenti immaginativi e terapie artistiche che sfruttano tutti i linguaggi della creativit\u00e0.\u00a0Le sue performance sono atti poetici finalizzati alla conoscenza e alla trasformazione di se stessi.\u00a0Nello studio dove l\u2019artista opera, in Abruzzo, conduce workshop che integrano performance, fotografia, grafica, metagenealogia, psicologia. Ospita anche incontri, lezioni, talk. Altre volte ancora, Mandra rimane a guardare il mare. Le principali mostre e altre info:\u00a0<\/em><br \/><em><a href=\"http:\/\/www.mandracerrone.com\">www.mandracerrone.com<\/a><\/em><br \/><\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">INFO<br \/><strong>Mater Dolorosa<\/strong><br \/>Performance Art di e con Mandra Cerrone<br \/>A cura di Michela Becchis<br \/><br \/>Con la partecipazione di:\u00a0Annie Di Sante Marolli, Clarisa Gil, Daniela Aubrechtova, Donatella D\u2019Emilio, Mania Mehrabi, Zuleika Fusco<br \/>Foto\u00a0Manuel Vallescura<br \/>Riprese video\u00a0Bruno Imbastaro<br \/><br \/>Partner: Mystic Driver Art lab, Leo\u2019s Bioparrucchiere, Yoga Center Elisa, I Luoghi dell\u2019Anima, L\u2019Isola di Amantani, Cietta Studio<br \/>2 ottobre 2018 ore 18.00<br \/><br \/>Aurum - Sala D\u2019Annunzio<br \/>Largo Gardone Riviera - Pescara (PE)<br \/>Ingresso libero<strong><br \/><\/strong><\/pre>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">\u23f0 lettura <\/span> <span class=\"rt-time\"> 2<\/span> <span class=\"rt-label rt-postfix\">min. <\/p>\n<p><\/span><\/span>Il\u00a02 ottobre 2018 alle ore 18.00, presso l\u2019Aurum &#8211; Sala D\u2019Annunzio di Pescara, l\u2019Assessorato alla Cultura Citt\u00e0 di Pescara con l\u2019Associazione Mystic Driver Art Lab presenta Mater Dolorosa, performance art di e con Mandra Cerrone, a cura di Michela Becchis. Interverr\u00e0 Giovanni Di Iacovo, Assessore alla Cultura del Comune di Pescara. \u201cNulla come una performance&hellip;&nbsp;<a href=\"https:\/\/www.biancoscuro.it\/site\/mater-dolorosa-performance-art-di-e-con-mandra-cerrone\/\" rel=\"bookmark\">Leggi tutto &raquo;<span class=\"screen-reader-text\">Mater Dolorosa | Performance Art &#8211; Mandra Cerrone<\/span><\/a><\/p>\n","protected":false},"author":980,"featured_media":7863,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"footnotes":""},"categories":[5,26,676],"tags":[],"class_list":["post-7861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte","category-eventi","category-performance"],"jetpack_featured_media_url":"https:\/\/www.biancoscuro.it\/site\/wp-content\/uploads\/2018\/09\/Mater-Dolorosa-Mandra-Cerrone.jpg","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":12732,"url":"https:\/\/www.biancoscuro.it\/site\/claudio-di-carlo-detto-fatto\/","url_meta":{"origin":7861,"position":0},"title":"Claudio Di Carlo &#8211; Detto Fatto","author":"Roberta Melasecca","date":"13 Dicembre 2021","format":false,"excerpt":"In continuit\u00e0 con I pasticcini li porto io, mostra tenutasi a Roma nel 2020, Claudio Di Carlo, ospite del nuovo spazio espositivo pescarese GArt Gallery diretto da Francesco Di Matteo, presenta\u00a0Detto Fatto, mostra\/installazione\/happening\u00a0a cura di\u00a0Maria Arcidiacono.\u00a0 Detto Fattocostituisce il secondo appuntamento di un ciclo che, in questa occasione, vedr\u00e0 protagoniste\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/12\/CLAUDIO-DI-CARLO-DETTO-FATTO.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/12\/CLAUDIO-DI-CARLO-DETTO-FATTO.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/12\/CLAUDIO-DI-CARLO-DETTO-FATTO.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/12\/CLAUDIO-DI-CARLO-DETTO-FATTO.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2021\/12\/CLAUDIO-DI-CARLO-DETTO-FATTO.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":18083,"url":"https:\/\/www.biancoscuro.it\/site\/februare-la-performance-di-daiela-beltrani\/","url_meta":{"origin":7861,"position":1},"title":"Februare | performance di daiela Beltrani","author":"Roberta Melasecca","date":"25 Gennaio 2025","format":false,"excerpt":"Ultimo appuntamento del ciclo di eventi performativi \u2018Dal corpo al corpo dell\u2019arte\u2019a cura di Roberta Melasecca e Michela Becchis, realizzati nell\u2019ambito della mostra transdisciplinare IOSONOVULNERABILEdi Sergio Mario Illuminato: gioved\u00ec 6 febbraio 2025 alle ore 18.00, il Museo diVilla Altieri ospiter\u00e0la performance \u2018FEBRUARE\u2019 di Daniela Beltrani, azione realizzatain collaborazione con PAR\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/01\/Februare-la-performance-di-daiela-Beltrani.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/01\/Februare-la-performance-di-daiela-Beltrani.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/01\/Februare-la-performance-di-daiela-Beltrani.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":17989,"url":"https:\/\/www.biancoscuro.it\/site\/un-dono-performance-di-anahi-mariotti\/","url_meta":{"origin":7861,"position":2},"title":"Un dono &#8211; Performance di Anahi Mariotti","author":"Roberta Melasecca","date":"8 Gennaio 2025","format":false,"excerpt":"UN DONOPerformance di ANAHI MARIOTTI Dalle 17.30 alle 19.30, la loggia del Palazzo della Cultura e della Memoria Storica sar\u00e0 teatro della performance di Anahi Mariotti, dal titolo \u2018UN DONO\u2019, che appare permeata dallo stesso spirito che anima l\u2019allestimento del progetto \u2018iosonovulnerabile\u2019: l\u2019Atelier. Come scrive, infatti, Sergio Mario Illuminato nel\u2026","rel":"","context":"In &quot;eventi&quot;","block_context":{"text":"eventi","link":"https:\/\/www.biancoscuro.it\/site\/category\/eventi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/01\/INVITO-Un-dono-di-Anahi-Mariotti-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":18034,"url":"https:\/\/www.biancoscuro.it\/site\/cor-habeo-performance-di-francesca-di-ciaula\/","url_meta":{"origin":7861,"position":3},"title":"Cor Habeo | Francesca di Ciaula","author":"Roberta Melasecca","date":"17 Gennaio 2025","format":false,"excerpt":"Continua il ciclo di eventi performativi \u2018Dal corpo al corpo dell\u2019arte\u2019a cura di Roberta Melasecca e Michela Becchis, realizzati nell\u2019ambito di IOSONOVULNERABILEdi Sergio Mario Illuminato: gioved\u00ec 23 gennaio 2025 alle ore 18.00 la performance \u2018COR HABEO\u2019 di Francesca di Ciaula.\u00a0 \u00abFrancesca di Ciaula crede nel potere dell\u2019arte. E crede che\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/01\/INVITO-francesca-di-ciaula-copia.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/01\/INVITO-francesca-di-ciaula-copia.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/01\/INVITO-francesca-di-ciaula-copia.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/01\/INVITO-francesca-di-ciaula-copia.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":3475,"url":"https:\/\/www.biancoscuro.it\/site\/tpa-torino-performance-art\/","url_meta":{"origin":7861,"position":4},"title":"tpa torino PERFORMANCE ART &#8211; video performance section IV","author":"Redazione BIANCOSCURO","date":"15 Gennaio 2016","format":false,"excerpt":"Dal\u00a022 al\u00a024 gennaio\u00a0presso la\u00a0Galleria Moitre, via Santa Giulia 37, Torino e presso l'Atelier Giorgi, via Belfiore 5 H, Torino Il tpa festival, giunto alla sua quarta edizione, dedica tre giornate alla video performance internazionale. L\u2019evento, curato da Manuela Macco e Guido Salvini sar\u00e0 ospitato negli spazi della Galleria Moitre e\u2026","rel":"","context":"In &quot;arte&quot;","block_context":{"text":"arte","link":"https:\/\/www.biancoscuro.it\/site\/category\/arte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/01\/tpa-2015-piccola.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/01\/tpa-2015-piccola.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/01\/tpa-2015-piccola.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2016\/01\/tpa-2015-piccola.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":18051,"url":"https:\/\/www.biancoscuro.it\/site\/corpo-vestito-di-carta-performance-di-silvia-stucky\/","url_meta":{"origin":7861,"position":5},"title":"CORPO vestito DI CARTA | Silvia Stucky","author":"Roberta Melasecca","date":"26 Gennaio 2025","format":false,"excerpt":"Eventi Performativi \u2018Dal corpo al corpo dell\u2019arte\u2019a cura di Roberta Melasecca e Michela Becchisrealizzati nell\u2019ambito di IOSONOVULNERABILE Per il ciclo di eventi performativi \u2018Dal corpo al corpo dell\u2019arte\u2019a cura di Roberta Melasecca e Michela Becchis, realizzati nell\u2019ambito di IOSONOVULNERABILEdi Sergio Mario Illuminato, gioved\u00ec 30 gennaio 2025 alle ore 18.00, Villa\u2026","rel":"","context":"In &quot;eventi&quot;","block_context":{"text":"eventi","link":"https:\/\/www.biancoscuro.it\/site\/category\/eventi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.biancoscuro.it\/site\/wp-content\/uploads\/2025\/01\/silvia-stucky-1024x768-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/7861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/users\/980"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/comments?post=7861"}],"version-history":[{"count":0,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/7861\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/media\/7863"}],"wp:attachment":[{"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/media?parent=7861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/categories?post=7861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biancoscuro.it\/site\/wp-json\/wp\/v2\/tags?post=7861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}